{"id":15280,"date":"2016-08-15T12:49:57","date_gmt":"2016-08-15T11:49:57","guid":{"rendered":"https:\/\/amecorg.com\/amecframework\/home\/supporting-material\/expert-opinion\/"},"modified":"2025-01-20T13:07:49","modified_gmt":"2025-01-20T13:07:49","slug":"expert-opinion","status":"publish","type":"page","link":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/","title":{"rendered":"Expert Opinion"},"content":{"rendered":"<div class='clear'><\/div><div id='sub_menu1'  class='av-submenu-container av-1bru9h-7b236d28760a68799cbfdde49e986991 main_color  avia-builder-el-0  el_before_av_section  avia-builder-el-first  side-menu av-sticky-submenu container_wrap fullsize' style='z-index:301' ><div class='container av-menu-mobile-disabled av-submenu-pos-center'><ul id='av-custom-submenu-1' class='av-subnav-menu' role='menu'>\n<li class='menu-item av-1bj329-40755f515e7161286f0f4d2fcd9ce517 menu-item-top-level menu-item-top-level-1' role='menuitem'><a href='#proving-value'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>D\u00c9MONTRER LA VALEUR DANS UN MONDE INT\u00c9GR\u00c9<\/span><\/a><\/li>\n<li class='menu-item av-1ao9vp-ef9507e3ec52d018139b93a6e90c7af3 menu-item-top-level menu-item-top-level-2' role='menuitem'><a href='#why-measurement-matters'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>POURQUOI LA MESURE COMPTE<\/span><\/a><\/li>\n<li class='menu-item av-1a4elp-0049c130d7dd4c2e931536cdf9e2b6b8 menu-item-top-level menu-item-top-level-3' role='menuitem'><a href='#the-pesco-channel'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>LES CANAUX PESO<\/span><\/a><\/li>\n<li class='menu-item av-19ckip-eac94a8406db932943cbc6d9387ab1be menu-item-top-level menu-item-top-level-4' role='menuitem'><a href='#performance-public-relations'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>PERFORMANCE EN RELATIONS PUBLIQUES<\/span><\/a><\/li>\n<li class='menu-item av-18ti6d-3e12601a0d1d3d3ba8db323eb4bd63bb menu-item-top-level menu-item-top-level-5' role='menuitem'><a href='#if-your-failing'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>\u00ab SI VOUS NE PLANIFIEZ PAS, VOUS PLANIFIEZ VOTRE \u00c9CHEC \u00bb<\/span><\/a><\/li>\n<li class='menu-item av-18c7vl-1a62b0e7ce42f026093437b85be968fd menu-item-top-level menu-item-top-level-6' role='menuitem'><a href='#top-tips'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>CONSEILS PRATIQUES POUR LA PLANIFICATION ET LA D\u00c9FINITION DES OBJECTIFS<\/span><\/a><\/li>\n<li class='menu-item av-17y5e9-b15a5bc3aea24747bc9788793a278295 menu-item-top-level menu-item-top-level-7' role='menuitem'><a href='#measuring-reputation'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>MESURER LA R\u00c9PUTATION<\/span><\/a><\/li>\n<li class='menu-item av-4b799-9723ad1e4efcbaeb64dde7ff506ba35e menu-item-top-level menu-item-top-level-8' role='menuitem'><a href='#effectiveness-story'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>RACONTER L\u2018HISTOIRE DE L\u2019EFFECTIVIT\u00c9<\/span><\/a><\/li>\n<li class='menu-item av-16rz3x-b30d8533cf29aae0c24b2790fe761e1b menu-item-top-level menu-item-top-level-9' role='menuitem'><a href='#conclusion'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>CONCLUSIONS<\/span><\/a><\/li>\n<\/ul><\/div><\/div><div class='sticky_placeholder'><\/div>\n<div id='proving-value'  class='avia-section av-165d55-aabc9673f9927aec08a4653b221d3cc5 main_color avia-section-default avia-no-shadow  avia-builder-el-1  el_after_av_submenu  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-15jgbx-fae248d11d74df84be8e822517acbd5b\">\n.flex_column.av-15jgbx-fae248d11d74df84be8e822517acbd5b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-15jgbx-fae248d11d74df84be8e822517acbd5b av_one_third  avia-builder-el-2  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-14yqcd-3f51df5a9b6dd0473ec44c51ffbb9398\">\n.flex_column.av-14yqcd-3f51df5a9b6dd0473ec44c51ffbb9398{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-14yqcd-3f51df5a9b6dd0473ec44c51ffbb9398 av_two_third  avia-builder-el-3  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-14a401-e9f209d7719572a977bd7746aadc208d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>D\u00c9MONTRER LA VALEUR DANS UN MONDE INT\u00c9GR\u00c9<\/h2>\n<div id=\"u4637-6\" class=\"clearfix colelem shared_content\" data-content-guid=\"u4637-6_content\">\n<h3 id=\"u4637-4\">POURQUOI NOUS DEVONS PASSER D\u2019UNE MESURE CENTR\u00c9E UNIQUEMENT SUR LES R\u00c9SULTATS<\/h3>\n<\/div>\n<div id=\"u4637-6\" class=\"clearfix colelem shared_content\" data-content-guid=\"u4637-6_content\"><\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-13k8tt-e95a5fa32174f11125ee978ff64c7a30\">\n#top .hr.av-13k8tt-e95a5fa32174f11125ee978ff64c7a30{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-13k8tt-e95a5fa32174f11125ee978ff64c7a30 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-13k8tt-e95a5fa32174f11125ee978ff64c7a30 hr-custom  avia-builder-el-5  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-138ps5-73d711ed86e5765c4fd2a83deac992f4  avia-builder-el-6  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-90 avia-img-lazy-loading-not-90 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1.jpg\" alt='Richard Bagnall'  itemprop=\"image\"   height=\"92\" width=\"92\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1.jpg 92w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1-80x80.jpg 80w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1-36x36.jpg 36w\" sizes=\"(max-width: 92px) 100vw, 92px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/richardbagnall<\/span><a href='https:\/\/twitter.com\/richardbagnall' class='avia-team-icon av-12jpml-e1473706faad463d3d43e62dd127d016 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'  target='_blank' data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Richard Bagnall<\/h3><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-kp2ueg6x-3054c13eeef6bbd8093f7ef8bc371b76 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Richard Bagnall Co-Fondateur, <a href=\"https:\/\/commsclarity.com\/\">CommsClarity Consulting<\/a><\/strong><br \/>\nDirecteur du Conseil <a href=\"https:\/\/amecorg.com\/\">AMEC<\/a> Responsable du Cadre de l\u2019\u00c9valuation AMEC<\/p>\n<p>Il existe plusieurs raisons pour lesquelles l\u2019industrie doit d\u00e9passer son ancienne approche centr\u00e9e sur l\u2019analyse de contenu comme substitut \u00e0 la mesure des activit\u00e9s de communication. Que cela plaise ou non, nous vivons dans un monde o\u00f9 de nombreuses mesures autrefois consid\u00e9r\u00e9es comme des r\u00e9f\u00e9rences pour \u00e9valuer l\u2019efficacit\u00e9 des communications perdent leur pertinence.<\/p>\n<p>L\u2019univers m\u00e9diatique s\u2019\u00e9largit en termes de canaux et de plateformes, mais se r\u00e9tr\u00e9cit en termes d\u2019audience et d\u2019attention. Avec la fragmentation des canaux entre pay\u00e9s, gagn\u00e9s, partag\u00e9s et d\u00e9tenus, il devient de plus en plus difficile d\u2019interpr\u00e9ter avec pr\u00e9cision et de mani\u00e8re significative les anciennes mesures comme le volume, les impressions et la port\u00e9e.<\/p>\n<p>Il y a non seulement la difficult\u00e9 d\u2019obtenir des donn\u00e9es pr\u00e9cises de certains m\u00e9dias qui gardent ces informations priv\u00e9es, mais aussi, dans le monde num\u00e9rique, de nombreux chiffres sont faciles \u00e0 manipuler ou \u00e0 fausser. Par cons\u00e9quent, les volumes et impressions ne peuvent plus \u00eatre consid\u00e9r\u00e9s comme des mesures significatives, au-del\u00e0 de leur r\u00f4le d\u2019indicateurs g\u00e9n\u00e9raux.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=EhrXyl8glko&amp;t=41s&amp;ab_channel=CARMA\">En 2019, j\u2019ai donn\u00e9 une conf\u00e9rence \u00e0 Hong Kong dans les bureaux d\u2019Ogilvy RP o\u00f9 j\u2019ai approfondi ces d\u00e9fis et expliqu\u00e9 comment le cadre nous aide \u00e0 les surmonter gr\u00e2ce \u00e0 une approche moderne.<\/a><\/p>\n<\/div><\/section><br \/>\n<br \/>\n<section  class='av_textblock_section av-kp2ve33y-774d79ee1091082de74016b9275b78b1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Face \u00e0 ces d\u00e9fis, combin\u00e9s \u00e0 la nouvelle r\u00e9alit\u00e9 d\u2019un monde int\u00e9gr\u00e9 o\u00f9 les professionnels des RP doivent naviguer entre m\u00e9dias pay\u00e9s, gagn\u00e9s, partag\u00e9s et d\u00e9tenus, il est clair que notre fa\u00e7on de penser doit \u00e9voluer. Nous devons aller au-del\u00e0 des simples mesures de r\u00e9sultats pour d\u00e9montrer la valeur de nos efforts en examinant les r\u00e9actions, les r\u00e9sultats et les impacts organisationnels g\u00e9n\u00e9r\u00e9s par notre travail.<\/p>\n<p>Le Cadre d\u2019\u00c9valuation Int\u00e9gr\u00e9 de l\u2019AMEC fait pr\u00e9cis\u00e9ment cela \u2013 il propose une m\u00e9thode claire et facile \u00e0 suivre pour raconter l\u2019histoire d\u2019une excellente campagne de relations publiques (RP), depuis les objectifs jusqu\u2019aux publics cibles, en passant par la planification, les r\u00e9f\u00e9rences, les cibles, les activit\u00e9s, les r\u00e9sultats imm\u00e9diats, les r\u00e9actions, les r\u00e9sultats finaux et l\u2019impact organisationnel.<\/p>\n<p>Ce n\u2019est que lorsque le secteur des relations publiques (RP) cherchera \u00e0 mesurer l\u2019int\u00e9gralit\u00e9 de ses effets qu\u2019il pourra r\u00e9pondre de mani\u00e8re significative et cr\u00e9dible aux questions cl\u00e9s concernant ses performances.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='why-measurement-matters'  class='avia-section av-114hyd-62ba800729e4587cd99426eb693777fd main_color avia-section-default avia-no-shadow  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-10n871-986f2d1e02ce8009414e585ccad0bcb3\">\n.flex_column.av-10n871-986f2d1e02ce8009414e585ccad0bcb3{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-10n871-986f2d1e02ce8009414e585ccad0bcb3 av_one_third  avia-builder-el-11  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3lv55-042a0b5823a4759fb416faba9990fbdb\">\n.flex_column.av-3lv55-042a0b5823a4759fb416faba9990fbdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3lv55-042a0b5823a4759fb416faba9990fbdb av_two_third  avia-builder-el-12  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-zk6k9-d35a573e650b149574059b9fe1c2bafd '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>POURQUOI LA MESURE COMPTE<\/h2>\n<h3>LE POINT DE VUE DES AGENCES MONDIALES DE RP<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-yyx4p-a2bfaab1b83724a88c6974978fe32acd\">\n#top .hr.av-yyx4p-a2bfaab1b83724a88c6974978fe32acd{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-yyx4p-a2bfaab1b83724a88c6974978fe32acd .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-yyx4p-a2bfaab1b83724a88c6974978fe32acd hr-custom  avia-builder-el-14  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-kp2vexic-bc3b66b0e6e59f8058d18f0da755884a  avia-builder-el-15  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-91 avia-img-lazy-loading-not-91 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team.jpg\" alt='Giles Peddy'  itemprop=\"image\"   height=\"79\" width=\"81\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team.jpg 81w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team-80x79.jpg 80w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team-36x36.jpg 36w\" sizes=\"(max-width: 81px) 100vw, 81px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/GilesPeddy<\/span><a href='https:\/\/twitter.com\/GilesPeddy' class='avia-team-icon av-y1jqp-eb6aabc3e6f91dbc1f16e650ae98640f twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Giles Peddy<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>PDG, Missive PR<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-3ctix-3a165889a6bcc1981f9654fe96ac8a2e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Pendant de nombreuses ann\u00e9es, le mot \u00ab mesure \u00bb faisait fuir les professionnels de la communication. Ou les poussait \u00e0 prendre un verre. Je peux presque le voir : des papiers qu\u2019on brasse maladroitement, un raclement de gorge, et une tentative d\u00e9sesp\u00e9r\u00e9e d\u2019utiliser ce levier sur la chaise qui ne semble avoir aucune fonction \u00e9vidente. Tout pour \u00e9viter la v\u00e9rit\u00e9 g\u00eanante que nous n\u2019avons pas \u00e9t\u00e9 excellents en mati\u00e8re de mesure.<\/p>\n<p>Cependant, les temps changent. La reconnaissance croissante de la valeur strat\u00e9gique des communications dans les conseils d\u2019administration, combin\u00e9e aux exigences toujours plus fortes de justification budg\u00e9taire li\u00e9e \u00e0 l\u2019impact commercial, a rendu la mesure incontournable.<\/p>\n<p>Cependant, je soutiendrais encore que le manque de processus, de m\u00e9thodologie, de normes ou d\u2019une taxonomie claire de ce qui constitue une bonne mesure a frein\u00e9 l\u2019industrie. Cela est particuli\u00e8rement vrai au sein des agences, qui r\u00e9alisent souvent une grande partie du travail de mesure et d\u2019\u00e9valuation, en collaboration avec des prestataires tiers.<\/p>\n<p>Cette faible adoption d\u2019un cadre de mesure clair signifie que, dans de nombreux cas, les mesures se concentrent sur les r\u00e9sultats des RP et les r\u00e9sultats interm\u00e9diaires. Mais qu\u2019en est-il des r\u00e9sultats commerciaux ? Quel a \u00e9t\u00e9 l\u2019impact de cette campagne ou activit\u00e9 sur la notori\u00e9t\u00e9 ? A-t-elle renforc\u00e9 l\u2019plaidoyer ? A-t-elle entra\u00een\u00e9 une adoption accrue par les utilisateurs finaux ? A-t-elle conduit \u00e0 une augmentation de la demande pour le produit ou service ?<\/p>\n<p>Ce niveau de mesure reste minoritaire (bien qu\u2019en croissance). Mais selon moi, et c\u2019est l\u00e0 un point de vue d\u2019agence, nous devons toujours poser, et surtout r\u00e9pondre, \u00e0 cette question simple : \u00ab En quoi ce travail va-t-il aider l\u2019entreprise de notre client ? \u00bb<\/p>\n<p>Quel que soit l\u2019objectif commercial, c\u2019est sur celui-ci que nous devons nous concentrer et que nous devons mesurer. Comprendre ce qui compte pour l\u2019entreprise nous permet de mieux construire un cadre de mesures pertinent.<br \/>\nC\u2019est pourquoi le nouveau Cadre Interactif des Mesures Valid\u00e9es de l\u2019Association Internationale pour la Mesure et l\u2019\u00c9valuation des Communications (AMEC) est si essentiel pour les agences (et les \u00e9quipes internes c\u00f4t\u00e9 client) \u00e0 adopter et int\u00e9grer. Ce nouveau cadre interactif fournit aux utilisateurs une m\u00e9thodologie claire et une taxonomie pour d\u00e9velopper un plan de communication clair et mesurable, et pour en \u00e9valuer le succ\u00e8s. Il offre aux utilisateurs de l\u2019outil un parcours structur\u00e9 et, surtout, une mani\u00e8re de d\u00e9montrer l\u2019impact organisationnel.<\/p>\n<p>Beaucoup diront que pour montrer les r\u00e9sultats organisationnels, il faut obtenir des donn\u00e9es provenant de plusieurs d\u00e9partements de l\u2019organisation. Oui, c\u2019est vrai. Mais en utilisant l\u2019outil interactif, vous saurez au moins quelles sont ces mesures cl\u00e9s, qui en est responsable, et comment elles s\u2019int\u00e8grent dans les efforts de communication int\u00e9gr\u00e9e que vous affirmez fournir \u00e0 vos clients.<\/p>\n<p>C\u2019est pourquoi les clients doivent nous \u00ab montrer les donn\u00e9es \u00bb. Si nous avons acc\u00e8s aux donn\u00e9es, nous pouvons mesurer notre travail de mani\u00e8re beaucoup plus strat\u00e9gique. Cela repr\u00e9sente une opportunit\u00e9 pour les professionnels qualifi\u00e9s de d\u00e9couvrir de nouvelles perspectives susceptibles d\u2019informer une campagne, de changer une approche et d\u2019obtenir un impact plus fort. Bien s\u00fbr, il est parfois difficile de montrer ce que chaque \u00e9l\u00e9ment individuel du mix marketing a apport\u00e9, mais utiliser les bons outils donne g\u00e9n\u00e9ralement une bonne id\u00e9e des r\u00e9sultats. Finalement, lorsqu\u2019il y a un cadre clair, il y a un chemin.<\/p>\n<p>Ainsi, m\u00eame si la conversation autour de la mesure peut sembler inconfortable pour beaucoup, je dis : ne la laissez pas l\u2019\u00eatre. Placez-la au c\u0153ur de vos priorit\u00e9s et utilisez-la pour alimenter des discussions organisationnelles pertinentes. Utilisez le nouveau Cadre Interactif des Mesures Valid\u00e9es de l\u2019AMEC comme votre boussole. Les vents du changement soufflent. Ajustez vos voiles et avancez vers un nouveau monde de la mesure.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='the-pesco-channel'  class='avia-section av-x2m0x-c91598ad730978c1ed52432aea2cb151 main_color avia-section-default avia-no-shadow  avia-builder-el-17  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-w9ind-005e5ddacc510b7911080e5c23dadd46\">\n.flex_column.av-w9ind-005e5ddacc510b7911080e5c23dadd46{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-w9ind-005e5ddacc510b7911080e5c23dadd46 av_one_third  avia-builder-el-18  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-vtb8l-5d93654cd1965245fdebc04f71a49344\">\n.flex_column.av-vtb8l-5d93654cd1965245fdebc04f71a49344{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-vtb8l-5d93654cd1965245fdebc04f71a49344 av_two_third  avia-builder-el-19  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-vi9xt-fd9d8972f73ca696b2741cbd6660149f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 id=\"u5962-2\">LES CANAUX PESO : CE QU\u2019ILS SONT ET POURQUOI ILS SONT IMPORTANTS<\/h2>\n<h3 id=\"u5962-4\"><\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-urupd-0ee4521e55de1db65943e7859e80b807\">\n#top .hr.av-urupd-0ee4521e55de1db65943e7859e80b807{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-urupd-0ee4521e55de1db65943e7859e80b807 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-urupd-0ee4521e55de1db65943e7859e80b807 hr-custom  avia-builder-el-21  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-kp2vfdh3-4637d4b1fe53378d1f0bd8f0f5b4134b  avia-builder-el-22  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-93 avia-img-lazy-loading-not-93 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/gini-dietrich.jpg\" alt='Gini Dietrich'  itemprop=\"image\"   height=\"100\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/ginidietrich<\/span><a href='https:\/\/twitter.com\/ginidietrich' class='avia-team-icon av-ubdkl-3eb8f41f028695c2222cf475d19d1cd0 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Gini Dietrich<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Fondatrice<br \/>\nSpin Sucks<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-tf605-df7d6957d0cb6815c44092e472edc93d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u5992-5\"><span style=\"font-weight: 400;\">Selon <\/span><a class=\"nonblock\" href=\"http:\/\/www.biography.com\/people\/henry-ford-9298747\" target=\"_blank\" rel=\"noopener\"><span id=\"u5992-2\">Henry Ford<\/span><\/a>, \u00ab Se rassembler est un d\u00e9but ; rester ensemble est un progr\u00e8s ; travailler ensemble est un succ\u00e8s. \u00bb Cette citation peut s\u2019appliquer \u00e0 tout type d\u2019environnement de travail, y compris dans les agences de relations publiques ou les d\u00e9partements de communication. Mais elle ne s\u2019applique pas seulement aux organisations ; elle peut \u00e9galement s\u2019appliquer \u00e0 une strat\u00e9gie de communication.<\/p>\n<p>C\u2019est pourquoi le <a class=\"nonblock\" href=\"http:\/\/spinsucks.com\/communication\/pr-pros-must-embrace-the-peso-model\/\" target=\"_blank\" rel=\"noopener\"><span id=\"u5992-7\">mod\u00e8le PESO<\/span><\/a><\/p>\n<p>a vu le jour. PESO repr\u00e9sente les m\u00e9dias payants, acquis, partag\u00e9s et d\u00e9tenus, et il adopte une approche int\u00e9gr\u00e9e de la communication afin que nous puissions mesurer nos efforts en fonction des \u00e9l\u00e9ments qui comptent vraiment pour les organisations, comme l\u2019acquisition de nouveaux clients, l\u2019augmentation des revenus, l\u2019am\u00e9lioration des profits ou l\u2019obtention de nouveaux donateurs. Il est temps de consid\u00e9rer nos efforts comme un investissement plut\u00f4t que comme une d\u00e9pense, et le mod\u00e8le PESO \u2013 lorsqu\u2019il est utilis\u00e9 correctement \u2013 vous y conduira.<\/p>\n<p>Contrairement \u00e0 une cha\u00eene de montage de fabrication de voitures, vous allez commencer \u00e0 la fin\u2026 ou avec les m\u00e9dias d\u00e9tenus.<\/p>\n<p>Dans le monde actuel, presque rien ne fonctionne sans que les m\u00e9dias d\u00e9tenus soient au centre de votre programme de communication. Les journalistes veulent savoir que vos experts ont \u00e9t\u00e9 publi\u00e9s ailleurs. Vous n\u2019avez rien \u00e0 partager sur les r\u00e9seaux sociaux sans m\u00e9dias d\u00e9tenus. Vous n\u2019avez pas grand-chose \u00e0 annoncer en ligne si vous n\u2019avez pas de contenu \u00e0 promouvoir. Et le marketing par courriel produit un bruit sourd si vous ne partagez rien de pr\u00e9cieux. Les m\u00e9dias d\u00e9tenus sont au c\u0153ur de tout ce que vous faites, et il est impossible d\u2019avoir un programme int\u00e9gr\u00e9 sans eux.<\/p>\n<p>Une fois que vous avez une biblioth\u00e8que solide de m\u00e9dias d\u00e9tenus, il est temps de le crier sur tous les toits. En 2016, cela signifie utiliser les m\u00e9dias partag\u00e9s (r\u00e9seaux sociaux) pour la distribution et la promotion.<\/p>\n<p>Il y a une nouvelle plateforme de m\u00e9dias sociaux qui appara\u00eet chaque jour, et vous n\u2019\u00eates pas oblig\u00e9 d\u2019\u00eatre sur toutes. En fait, vous ne devriez pas \u00eatre sur toutes. Faites vos recherches et \u00e9tablissez votre pr\u00e9sence sur celles qui ont du sens pour vos objectifs.<\/p>\n<p>Nous travaillons \u00e0 l\u2019envers, donc les m\u00e9dias acquis devraient \u00eatre les suivants, mais ils viennent en dernier. Le canal suivant sur lequel se concentrer est le m\u00e9dia pay\u00e9, qui est exactement ce qu\u2019il semble \u00eatre. C\u2019est votre chance d\u2019amplifier votre message gr\u00e2ce \u00e0 la publicit\u00e9 et d\u2019atteindre de nouveaux publics pour aussi peu que 5 $ par jour sur chaque plateforme. Facebook, LinkedIn et Twitter ont leurs propres options publicitaires natives, et ils offrent g\u00e9n\u00e9ralement des coupons pour les d\u00e9butants, ce qui est encore plus incitatif pour essayer.<\/p>\n<p>Vous ne voulez pas mettre de l\u2019argent derri\u00e8re chaque publication, alors testez-le une fois par mois sur chaque plateforme. Il existe bien s\u00fbr d\u2019autres fa\u00e7ons d\u2019amplifier vos m\u00e9dias d\u00e9tenus, comme le marketing par courriel, les blogs invit\u00e9s ou le contenu contribu\u00e9.<\/p>\n<p>En parlant d\u2019influenceurs, il est maintenant temps de parler des m\u00e9dias acquis. Aucun inconnu pour les communicateurs, les relations que vous gagnez sont pr\u00e9cieuses pour la cr\u00e9dibilit\u00e9 de tiers. Le pouvoir du bouche-\u00e0-oreille est ind\u00e9niable, c\u2019est pourquoi les m\u00e9dias acquis sont un \u00e9l\u00e9ment crucial pour gagner en autorit\u00e9. Ces relations prennent du temps, de la confiance et de la diligence, donc les m\u00e9dias acquis ne vous donneront pas de r\u00e9sultats imm\u00e9diats, mais lorsqu\u2019ils sont int\u00e9gr\u00e9s avec les autres types de m\u00e9dias, ils donneront des r\u00e9sultats plus rapidement que s\u2019ils sont utilis\u00e9s seuls.<\/p>\n<p>Le mod\u00e8le PESO n\u2019est pas une strat\u00e9gie universelle, mais comme la cha\u00eene de montage, il n\u00e9cessite que tous l<a href=\"http:\/\/mashable.com\/2014\/12\/05\/public-relations-industry\/\">es canaux fonctionnent ensemble<\/a> pour obtenir de vrais r\u00e9sultats commerciaux.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='performance-public-relations'  class='avia-section av-soyy5-44abc7049e97b549162f7c178646ef1d main_color avia-section-default avia-no-shadow  avia-builder-el-24  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-sghxl-5eea4afa36551b9b5e267b742b012b38\">\n.flex_column.av-sghxl-5eea4afa36551b9b5e267b742b012b38{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-sghxl-5eea4afa36551b9b5e267b742b012b38 av_one_third  avia-builder-el-25  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ruhyh-72ef04c651d70fb0bab751b483ee39e6\">\n.flex_column.av-ruhyh-72ef04c651d70fb0bab751b483ee39e6{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ruhyh-72ef04c651d70fb0bab751b483ee39e6 av_two_third  avia-builder-el-26  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-r1ftd-3a41d2a1708b14b410d1ab711ca982c9 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\">PERFORMANCE EN RELATIONS PUBLIQUES<\/h2>\n<p id=\"u6003-4\">EXTRAIRE LES DONN\u00c9ES DES SILOS AU SEIN DE VOTRE ORGANISATION EST CRUCIAL POUR UNE PERFORMANCE EN RELATIONS PUBLIQUES D\u2019EXCELLENCE.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-qqo31-f415d4da46e8581a1af2361166973d8e\">\n#top .hr.av-qqo31-f415d4da46e8581a1af2361166973d8e{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-qqo31-f415d4da46e8581a1af2361166973d8e .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-qqo31-f415d4da46e8581a1af2361166973d8e hr-custom  avia-builder-el-28  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-kp2vgd5v-1c53fe9832cd811d6e0a67474563bc5a  avia-builder-el-29  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-94 avia-img-lazy-loading-not-94 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington.jpg\" alt='Stephen Waddington'  itemprop=\"image\"   height=\"79\" width=\"79\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington.jpg 79w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington-36x36.jpg 36w\" sizes=\"(max-width: 79px) 100vw, 79px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/wadds<\/span><a href='https:\/\/twitter.com\/wadds' class='avia-team-icon av-q00d1-a891810f1971bcde53e2dae963bba372 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Stephen Waddington<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Stephen est le fondateur de Wadds Inc. Il est professeur invit\u00e9 \u00e0 l\u2019Universit\u00e9 de Newcastle. Il blogge sur wadds.co.uk.<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-p8mbt-2ce6ace07b200c1d3373e7c22599a454 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Il existe une croyance selon laquelle mesurer notre travail en relations publiques est co\u00fbteux. Le manque de budget est souvent cit\u00e9 comme la raison de la mauvaise mesure. Mais le plus grand co\u00fbt pour la performance de votre organisation, et pour votre propre d\u00e9veloppement, est de ne pas mesurer le succ\u00e8s de votre travail.<\/p>\n<h4 id=\"u6033-6\">MESURER LA PERFORMANCE ORGANISATIONNELLE, PAS LES M\u00c9DIAS<\/h4>\n<p>Le secteur de la mesure des relations publiques s\u2019est construit sur des mesures traditionnelles des m\u00e9dias. Celles-ci ne sont plus adapt\u00e9es. Au mieux, elles repr\u00e9sentent un mauvais indicateur de substitution de la performance commerciale.<br \/>\n\u00c0 mesure que la pratique \u00e9volue, passant des m\u00e9dias traditionnels en tant que forme principale d\u2019engagement en relations publiques, vers une vari\u00e9t\u00e9 de m\u00e9dias num\u00e9riques et sociaux, les entreprises deviennent plus intelligentes dans la mesure de leurs performances.<\/p>\n<p>Les m\u00e9dias payants, acquis, d\u00e9tenus et partag\u00e9s laissent tous une trace d\u2019audit qui peut \u00eatre interrog\u00e9e.<\/p>\n<p>Notre opportunit\u00e9 est de d\u00e9finir des objectifs solides, des sorties et des r\u00e9sultats pour une campagne, puis d\u2019appliquer un cadre et des outils de mesure. Nous avons maintenant acc\u00e8s, comme jamais auparavant, \u00e0 des sources de donn\u00e9es et des outils pour mesurer les retomb\u00e9es et les r\u00e9sultats.<\/p>\n<h4 id=\"u6033-18\">EXTRAIRE LES DONN\u00c9ES DES SILOS DEPARTEMENTAUX<\/h4>\n<p>Le d\u00e9fi est que les donn\u00e9es sont souvent enfouies dans des silos au sein d\u2019une organisation. Les budgets d\u00e9partementaux et les d\u00e9limitations politiques ont la priorit\u00e9 sur la d\u00e9monstration des performances.<\/p>\n<p>Je vous encourage \u00e0 traverser les silos de votre organisation et \u00e0 extraire les donn\u00e9es. Les relations publiques doivent travailler avec le service client, le marketing et les ressources humaines.<\/p>\n<p>Voici 30 endroits o\u00f9 vous pouvez chercher des donn\u00e9es au sein de votre organisation pour \u00e9tablir un cadre de mesure solide.<\/p>\n<h4 id=\"u6033-26\">R\u00c9SULTATS INTERM\u00c9DIAIRES<\/h4>\n<div id=\"u6033-96\" class=\"ts-Default-Link-Style--copy clearfix grpelem shared_content\" data-content-guid=\"u6033-96_content\">\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Article<\/b><span style=\"font-weight: 400;\"> \u2013 volume d\u2019articles ou de publications de tiers, li\u00e9s aux r\u00e9sultats, utile pour les comparaisons avec les campagnes pr\u00e9c\u00e9dentes.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Participation<\/b><span style=\"font-weight: 400;\"> \u2013 consommateurs ou citoyens participant \u00e0 un \u00e9v\u00e9nement tel qu\u2019une conf\u00e9rence, une table ronde ou une r\u00e9union publique.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Recherche de marque<\/b><span style=\"font-weight: 400;\"> \u2013 augmentation de l\u2019activit\u00e9 de recherche autour d\u2019une marque \u00e0 la suite d\u2019une activit\u00e9 de relations publiques.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Conversation<\/b><span style=\"font-weight: 400;\"> \u2013 lier \u00e0 un r\u00e9sultat organisationnel sinon c\u2019est une mesure de vanit\u00e9, comme beaucoup de la mesure des m\u00e9dias sociaux.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>T\u00e9l\u00e9chargement<\/b><span style=\"font-weight: 400;\"> \u2013 forme de prospect r\u00e9sultant d\u2019un appel \u00e0 l\u2019action. Capturer les donn\u00e9es pour une gestion continue ou un remarketing.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Temps de s\u00e9jour<\/b><span style=\"font-weight: 400;\"> \u2013 temps pass\u00e9 sur une page web. Utile pour distinguer entre un trafic brut et un visiteur qui a effectivement lu le contenu de la page.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Clics sur les courriels<\/b><span style=\"font-weight: 400;\"> \u2013 utilis\u00e9 pour d\u00e9terminer si un destinataire d\u2019email a bien re\u00e7u et agi selon l\u2019appel \u00e0 l\u2019action.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Abonn\u00e9s<\/b><span style=\"font-weight: 400;\"> \u2013 construction d\u2019une audience ou d\u2019une communaut\u00e9 autour d\u2019une marque. Le taux de croissance est \u00e9galement un bon indicateur.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Visites ou vues<\/b><span style=\"font-weight: 400;\"> \u2013 un indicateur de la visite d\u2019une page web, mais attention au trafic frauduleux ou non pertinent. \u00c0 utiliser avec le temps de s\u00e9jour comme indicateur d\u2019engagement r\u00e9el.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Liens entrants<\/b><span style=\"font-weight: 400;\"> \u2013 qualit\u00e9 et volume de liens entrants vers une URL pr\u00e9d\u00e9finie. Li\u00e9 au trafic. Fr\u00e9quemment utilis\u00e9 dans les campagnes de recherche.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Like\/J\u2019aime<\/b><span style=\"font-weight: 400;\"> \u2013 souvent une mesure de vanit\u00e9 des m\u00e9dias sociaux, mais utile si une corr\u00e9lation avec un autre indicateur interm\u00e9diaire ou un r\u00e9sultat organisationnel est observ\u00e9e.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Trafic r\u00e9f\u00e9rent<\/b><span style=\"font-weight: 400;\"> \u2013 trafic provenant de sites web tiers, souvent utilis\u00e9 en aval avec les liens entrants.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Avis<\/b><span style=\"font-weight: 400;\"> \u2013 forme de validation tierce qui se r\u00e9pand des secteurs de l\u2019h\u00f4tellerie et du tourisme vers d\u2019autres industries.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Sentiment<\/b><span style=\"font-weight: 400;\"> \u2013 savoir si c\u2019est positif ou n\u00e9gatif est g\u00e9n\u00e9ralement tout ce que vous devez savoir, sauf si vous travaillez sur le changement d\u2019opinion sur un sujet au fil du temps.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Part de voix<\/b><span style=\"font-weight: 400;\"> \u2013 volume de conversations sur les m\u00e9dias sociaux ou traditionnels pour une organisation par rapport \u00e0 une organisation concurrente.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Volume de partages<\/b><span style=\"font-weight: 400;\"> \u2013 taux de partage sur les m\u00e9dias sociaux via diff\u00e9rents canaux. Lier les canaux au comportement et aux r\u00e9sultats.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Recherche non marqu\u00e9e<\/b><span style=\"font-weight: 400;\"> \u2013 augmentation ou contribution \u00e0 l\u2019activit\u00e9 de recherche autour d\u2019un terme \u00e0 la suite de l\u2019activit\u00e9 de relations publiques.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Afflux<\/b><span style=\"font-weight: 400;\"> \u2013 nombre de personnes ayant voyag\u00e9 ou visit\u00e9 un lieu, fr\u00e9quemment utilis\u00e9 dans les secteurs du voyage, du tourisme et de l\u2019h\u00f4tellerie.<\/span><\/li>\n<\/ol>\n<div id=\"pu6033-96\" class=\"clearfix colelem\">\n<div id=\"u6038-4\" class=\"ts-Default-Link-Style--copy clearfix grpelem shared_content\" data-content-guid=\"u6038-4_content\">\n<p id=\"u6038-2\"><strong>R\u00c9SULTATS ORGANISATIONNELS<\/strong><\/p>\n<\/div>\n<\/div>\n<ol id=\"u6033-87\" class=\"list0 nls-None\" style=\"counter-reset: section;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Changement d\u2019attitude<\/b><span style=\"font-weight: 400;\"> \u2013 une vari\u00e9t\u00e9 de techniques de sondage avant et apr\u00e8s utilis\u00e9es pour tester un changement d\u2019opinion. Populaire dans les sondages politiques.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Sensibilisation\/notori\u00e9t\u00e9<\/b><span style=\"font-weight: 400;\"> \u2013 engagement d\u2019un public qui \u00e9tait auparavant inconscient d\u2019un probl\u00e8me, produit ou service. Test\u00e9 via diverses techniques de sondage.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Changement comportemental<\/b><span style=\"font-weight: 400;\"> \u2013 am\u00e9liorations socio-\u00e9conomiques telles que la r\u00e9duction des comportements antisociaux, test\u00e9es via des suivis longitudinaux.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Processus commerciaux<\/b><span style=\"font-weight: 400;\"> \u2013 am\u00e9lioration de la productivit\u00e9, g\u00e9n\u00e9ralement due \u00e0 la communication interne et \u00e0 la formation.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Conversions<\/b><span style=\"font-weight: 400;\"> \u2013 ventes typiques, mais \u00e9galement applicable \u00e0 d\u2019autres activit\u00e9s organisationnelles, pouvant \u00eatre attribu\u00e9es \u00e0 une activit\u00e9 de relations publiques.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Performance financi\u00e8re<\/b><span style=\"font-weight: 400;\"> \u2013 suivre le r\u00f4le des relations publiques dans le soutien d\u2019un indicateur financier tel que le cours de l\u2019action ou la valorisation.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Interne<\/b><span style=\"font-weight: 400;\"> \u2013 une s\u00e9rie de mesures comprenant l\u2019am\u00e9lioration du recrutement, de la r\u00e9tention et de la productivit\u00e9, et la r\u00e9duction de l\u2019absent\u00e9isme et des maladies.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Recommandation et r\u00e9f\u00e9rence<\/b><span style=\"font-weight: 400;\"> \u2013 la base du Net Promoter Score (score du promoteur net), qui mesure la probabilit\u00e9 d\u2019une recommandation ou d\u2019une r\u00e9f\u00e9rence de la part d\u2019un tiers (voir \u00e9galement satisfaction).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>R\u00e9tention<\/b><span style=\"font-weight: 400;\"> \u2013 s\u2019applique aux clients ou au personnel o\u00f9 les relations publiques sont centr\u00e9es sur la gestion des relations.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Satisfaction<\/b><span style=\"font-weight: 400;\"> \u2013 li\u00e9e \u00e0 la recommandation, utilis\u00e9e pour \u00e9valuer la force de la relation entre un citoyen ou un consommateur et une organisation.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>D\u00e9clencheurs uniques<\/b><span style=\"font-weight: 400;\"> \u2013 coupons, num\u00e9ros de t\u00e9l\u00e9phone ou URL d\u00e9di\u00e9s qui testent la relation entre l\u2019activit\u00e9 et les r\u00e9sultats.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Votes<\/b><span style=\"font-weight: 400;\"> \u2013 la r\u00e9alit\u00e9 des campagnes politiques o\u00f9 le test ultime de la r\u00e9ussite d\u2019une campagne se fait dans l\u2019isoloir.<\/span><\/li>\n<\/ol>\n<\/div>\n<ol id=\"u6033-87\" class=\"list0 nls-None\"><\/ol>\n<p><b>\u00c0 PROPOS DE STEPHEN WADDINGTON<\/b><\/p>\n<p id=\"u6033-94\">Stephen est partenaire et Directeur de l\u2019engagement chez Ketchum. Il est professeur invit\u00e9 \u00e0 l\u2019Universit\u00e9 de Newcastle. Il blogue sur\u00a0<a class=\"nonblock\" href=\"http:\/\/wadds.co.uk\/\" target=\"_blank\" rel=\"noopener\"><span id=\"u6033-91\">wadds.co.uk<\/span><\/a>.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='if-your-failing'  class='avia-section av-ozufl-e6dcee94fed516607219a24facbedc1f main_color avia-section-default avia-no-shadow  avia-builder-el-31  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-o0id5-dc85dca0139fcf75b084e173d1053338\">\n.flex_column.av-o0id5-dc85dca0139fcf75b084e173d1053338{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-o0id5-dc85dca0139fcf75b084e173d1053338 av_one_third  avia-builder-el-32  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ni5n1-76220855c5dd057cfb04cd3a7b8204c2\">\n.flex_column.av-ni5n1-76220855c5dd057cfb04cd3a7b8204c2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ni5n1-76220855c5dd057cfb04cd3a7b8204c2 av_two_third  avia-builder-el-33  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-mqki9-b114cb6749eed0f4e959dc8ff0e9dff1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\">\u00ab SI VOUS NE PLANIFIEZ PAS, VOUS PLANIFIEZ VOTRE \u00c9CHEC \u00bb<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mjbml-399ba68480e382a4345c949d448f8104\">\n#top .hr.av-mjbml-399ba68480e382a4345c949d448f8104{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-mjbml-399ba68480e382a4345c949d448f8104 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-mjbml-399ba68480e382a4345c949d448f8104 hr-custom  avia-builder-el-35  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-kp2vhcnz-ac4245462c691ccef7122508db298891  avia-builder-el-36  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-95 avia-img-lazy-loading-not-95 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Kevin-read.jpg\" alt='Kevin Read'  itemprop=\"image\"   height=\"95\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/readkevinread<\/span><a href='https:\/\/twitter.com\/readkevinread' class='avia-team-icon av-lr7fp-191e01a6af48c8e3d0325f02d7327d1d twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Kevin Read<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Directeur fondateur et PDG<br \/>\nPembroke and Rye<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-kwe3l-d4f1d263985304660bff68c70bee771f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Le nouveau cadre de mesures de l\u2019AMEC est une r\u00e9alisation remarquable qui ancre une r\u00e9flexion puissante, pertinente et utile de mani\u00e8re pratique et facile \u00e0 suivre.<\/p>\n<p>Pour Bell Pottinger, l\u2019un des nouveaux membres de l\u2019AMEC, il est particuli\u00e8rement utile pour d\u00e9finir un parcours que nos consultants peuvent suivre. Il facilite \u00e9galement les discussions avec les clients sur la mani\u00e8re d\u2019\u00e9tablir, planifier et rendre compte de l\u2019efficacit\u00e9 des campagnes.<\/p>\n<p>Avec l\u2019av\u00e8nement du num\u00e9rique et des m\u00e9dias sociaux comme canaux principaux, la complexit\u00e9 de nombreuses campagnes que nous menons a consid\u00e9rablement augment\u00e9. Cela signifie non seulement que nous devons comprendre comment mesurer l\u2019impact \u00e0 travers une gamme plus large de canaux de distribution, mais aussi que nous devons \u00eatre pleinement conscients des cons\u00e9quences des multiples points de contact.<\/p>\n<p>De m\u00eame, ce cadre continue de mettre l\u2019accent sur la compr\u00e9hension du contexte commercial et de la strat\u00e9gie qui sous-tendent les campagnes modernes. Planifier en fonction des objectifs organisationnels de mani\u00e8re claire et m\u00e9thodique avant toute activit\u00e9 est essentiel au succ\u00e8s.<\/p>\n<p>Dans les cabinets de conseil dot\u00e9s d\u2019une forte pratique consultative, l\u2019accent est mis sur la connaissance approfondie des affaires de nos partenaires et consultants, ainsi que des secteurs dans lesquels ils op\u00e8rent. Ces connaissances proviennent souvent d\u2019une analyse minutieuse des objectifs globaux de l\u2019organisation et du contexte dans lequel ils ont \u00e9t\u00e9 d\u00e9finis.<\/p>\n<p>Les analyses ax\u00e9es sur les diff\u00e9rentes approches sont \u00e9galement utiles. Comprendre comment les activit\u00e9s payantes, d\u00e9tenues et partag\u00e9es s\u2019articulent les unes avec les autres donne au planificateur en communication une vue plus compl\u00e8te des synergies potentielles entre les canaux.<\/p>\n<p>Dans les \u00e9quipes hybrides, avec la repr\u00e9sentation de diff\u00e9rentes agences, il peut parfois y avoir des d\u00e9fis importants pour rassembler toutes les donn\u00e9es de planification pertinentes. La capture des r\u00e9sultats multicanaux peut \u00e9galement \u00eatre difficile.<br \/>\nL\u2019accent mis sur l\u2019analyse des r\u00e9actions initiales d\u2019un public aux communications, des effets subs\u00e9quents et des impacts \u00e0 long terme demeure un mod\u00e8le solide et robuste avec lequel les cabinets de conseil peuvent travailler. L\u2019art de ce mod\u00e8le est de toujours \u00eatre parfaitement clair sur l\u2019indicateur ou le jalon que vous tentez de mesurer.<\/p>\n<p>Il reste n\u00e9cessaire d\u2019\u00eatre prudent quant \u00e0 la causalit\u00e9 ; cependant, il est encourageant de constater que les impacts \u00e0 long terme sont fermement ax\u00e9s sur la r\u00e9putation, les relations et le changement.<\/p>\n<p>Chez Bell Pottinger, nous recommandons en toute confiance le nouveau cadre de l\u2019AMEC \u00e0 nos partenaires et consultants au sein de l\u2019entreprise.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='top-tips'  class='avia-section av-ku2ot-a65023ab9f153fe515ee04f90ecb8988 main_color avia-section-default avia-no-shadow  avia-builder-el-38  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jpxh1-88242e2cb15bf09df02e3a03642f2870\">\n.flex_column.av-jpxh1-88242e2cb15bf09df02e3a03642f2870{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-jpxh1-88242e2cb15bf09df02e3a03642f2870 av_one_third  avia-builder-el-39  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jl1s1-21b38f86ba0162f6e734591b4c6c4f1c\">\n.flex_column.av-jl1s1-21b38f86ba0162f6e734591b4c6c4f1c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-jl1s1-21b38f86ba0162f6e734591b4c6c4f1c av_two_third  avia-builder-el-40  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-iypgh-99cb4e3db351e6e93078493370a36384 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\">CONSEILS PRATIQUES POUR LA PLANIFICATION ET LA D\u00c9FINITION DES OBJECTIFS<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-id4dh-9c0ce28b50a6561aae5f52748a2de180\">\n#top .hr.av-id4dh-9c0ce28b50a6561aae5f52748a2de180{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-id4dh-9c0ce28b50a6561aae5f52748a2de180 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-id4dh-9c0ce28b50a6561aae5f52748a2de180 hr-custom  avia-builder-el-42  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-hj0yp-a9ccd2f733ea60e5e3410eae5039cee6  avia-builder-el-43  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-96 avia-img-lazy-loading-not-96 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/elayne-phillips.jpg\" alt='Elayne Phillips'  itemprop=\"image\"   height=\"79\" width=\"99\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/layneyp<\/span><a href='https:\/\/twitter.com\/layneyp' class='avia-team-icon av-grd7h-8acf2aeae590bef61d32046af8e7d701 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Elayne Phillips<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Responsable des communications du service public et des communications internes, Bureau du Premier ministre et Bureau du Cabinet, et membre du conseil de l\u2019AMEC.<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-1matx-07abd0a0e4102b0b98cddb96f6ce77a1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 id=\"u6166-2\">L\u2019IMPORTANCE DE LA PLANIFICATION ET DE LA D\u00c9FINITION DES OBJECTIFS<\/h4>\n<p>Une bonne mesure et \u00e9valuation peuvent r\u00e9v\u00e9ler des informations pr\u00e9cieuses qui guideront vos actions futures. Les r\u00e9sultats peuvent modifier l\u2019orientation de votre campagne et influencer les canaux sur lesquels vous choisirez d\u2019investir vos efforts \u00e0 l\u2019avenir, ainsi que ceux que vous d\u00e9ciderez de ne pas utiliser.<\/p>\n<p>Pour maximiser les avantages de l\u2019\u00e9valuation des communications, il est essentiel de planifier. D\u00e8s que possible, planifiez ce que vous allez mesurer, en vous rappelant de mesurer ce qui compte en fonction de vos objectifs, et mettez en place les m\u00e9canismes n\u00e9cessaires pour suivre les bonnes mesures d\u00e8s le d\u00e9part. Voici pourquoi cela est important :<\/p>\n<p>Si vous ne d\u00e9finissez pas d\u00e8s le d\u00e9but ce qu\u2019il est important de suivre, vous risquez de constater plus tard qu\u2019il est impossible de r\u00e9cup\u00e9rer les donn\u00e9es n\u00e9cessaires de mani\u00e8re r\u00e9trospective.<\/p>\n<p>La planification de vos activit\u00e9s de mesure vous \u00e9vitera de perdre du temps \u00e0 suivre des mesures inutiles, voire des mesures de vanit\u00e9.<\/p>\n<p>Les plans de communication sont d\u2019autant plus cr\u00e9dibles lorsqu\u2019ils montrent clairement \u00e0 quoi ressemble le succ\u00e8s et comment il sera mesur\u00e9 et prouv\u00e9.<\/p>\n<p>Utilisez toujours les perspectives provenant des \u00e9valuations ant\u00e9rieures, lorsque cela est pertinent pour votre prochaine campagne, afin d\u2019aider \u00e0 d\u00e9finir vos objectifs. Lors de la phase de planification, la d\u00e9finition des objectifs vous apportera un cadre de travail clair et vous aidera \u00e0 suivre l\u2019\u00e9volution des r\u00e9sultats. Pensez donc \u00e0 bien r\u00e9fl\u00e9chir, \u00e0 d\u00e9finir des objectifs pr\u00e9cis et \u00e0 suivre les bonnes mesures de performance d\u00e8s le d\u00e9but de votre activit\u00e9.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='measuring-reputation'  class='avia-section av-fpaap-daf028f2287c950778409f613540bb1d main_color avia-section-default avia-no-shadow  avia-builder-el-45  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-f5n4d-ca8fe81b6aa17009f31e8f5866d7987c\">\n.flex_column.av-f5n4d-ca8fe81b6aa17009f31e8f5866d7987c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-f5n4d-ca8fe81b6aa17009f31e8f5866d7987c av_one_third  avia-builder-el-46  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ep0th-3a343af3a4ce7e7d4dd259b4f35af92d\">\n.flex_column.av-ep0th-3a343af3a4ce7e7d4dd259b4f35af92d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ep0th-3a343af3a4ce7e7d4dd259b4f35af92d av_two_third  avia-builder-el-47  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-1do3t-bbe0d7373ca5ddb0223a4c2697b94ead '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u6089-2\">MESURER LA R\u00c9PUTATION<\/h2>\n<h3>PR\u00c9FACE DE : AU-DEL\u00c0 DE LA MESURE DE LA R\u00c9PUTATION : UTILISER LA R\u00c9PUTATION POUR CR\u00c9ER DE LA VALEUR<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-defnp-a13b306ea9dbf88e5814c7d87f1d22af\">\n#top .hr.av-defnp-a13b306ea9dbf88e5814c7d87f1d22af{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-defnp-a13b306ea9dbf88e5814c7d87f1d22af .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-defnp-a13b306ea9dbf88e5814c7d87f1d22af hr-custom  avia-builder-el-49  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-cqnvd-a88dffe307241cbe15481fae398f7a8e  avia-builder-el-50  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-97 avia-img-lazy-loading-not-97 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/prof-kevin-money.jpg\" alt='Kevin Money'  itemprop=\"image\"   height=\"110\" width=\"79\" \/><\/div><h3 class='team-member-name '  itemprop=\"name\" >Kevin Money<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Professeur de R\u00e9putation et Leadership Responsable, Henley Business School<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-cbrdh-2ec186f446fd0cd4edcec9a1426064bd '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>La protection et l&rsquo;am\u00e9lioration de la r\u00e9putation sont des objectifs fr\u00e9quents que la communication est charg\u00e9e de soutenir. Le nouveau cadre int\u00e9gr\u00e9 d&rsquo;\u00e9valuation de l\u2019AMEC met clairement en \u00e9vidence l&rsquo;importance de mesurer la r\u00e9putation. Mais comment la mesurer de mani\u00e8re significative ? Comment la r\u00e9putation se lie-t-elle \u00e0 d&rsquo;autres crit\u00e8res de performance, tels que les classements et les tableaux de performance des entreprises les plus admir\u00e9es ? Comment savoir si votre r\u00e9putation aide ou freine votre organisation dans l&rsquo;atteinte de ses objectifs ? Comment utiliser la mesure de la r\u00e9putation pour guider la strat\u00e9gie de votre organisation ? Comment d\u00e9montrer que la r\u00e9putation apporte de la valeur aux parties prenantes importantes ? Comment comparer les diff\u00e9rents mod\u00e8les de mesure de la r\u00e9putation ? Et comment combiner ces mod\u00e8les pour g\u00e9n\u00e9rer des compr\u00e9hensions approfondies exploitables ? Enfin, comment pouvez-vous exploiter les donn\u00e9es existantes au sein de votre organisation pour d\u00e9montrer et am\u00e9liorer votre r\u00e9putation ?<\/p>\n<p>Dans cet article de masterclass, le professeur Kevin Money de la Henley Business School r\u00e9pond \u00e0 ces questions en pr\u00e9sentant la r\u00e9putation dans un mod\u00e8le de cr\u00e9ation de valeur. Cette approche pratique vous permettra de comparer vos m\u00e9thodes actuelles avec les meilleures pratiques. Elle vous aidera \u00e9galement \u00e0 identifier les causes et les cons\u00e9quences de la r\u00e9putation, ce qui peut guider les actions organisationnelles et les futures initiatives de mesure.<\/p>\n<p>Richard Bagnall et Kevin Money, juin 2016<\/p>\n<p id=\"u6119-10\"><a class=\"nonblock\" href=\"http:\/\/www.henley.reading.ac.uk\/web\/FILES\/corporate\/cl-White_Paper_Reputation_K_Money_C_Hillenbrand.pdf\" target=\"_blank\" rel=\"noopener\"><span id=\"u6119-8\">Cliquez ici pour lire le livre blanc \u00ab\u00a0Au-del\u00e0 de la mesure de la r\u00e9putation : utiliser la r\u00e9putation pour cr\u00e9er de la valeur\u00a0\u00bb<\/span><\/a><\/p>\n<p id=\"u6119-12\">Kevin Money et Carola Hillenbrand<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='effectiveness-story'  class='avia-section av-bf62l-294a37ac5717609944a2230e40c709c7 main_color avia-section-default avia-no-shadow  avia-builder-el-52  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b8qfp-359258220da71acfbde139c74e8ea389\">\n.flex_column.av-b8qfp-359258220da71acfbde139c74e8ea389{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-b8qfp-359258220da71acfbde139c74e8ea389 av_one_third  avia-builder-el-53  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ajsfx-e4cbc88db4f7f4d72bbd9caca9648e0c\">\n.flex_column.av-ajsfx-e4cbc88db4f7f4d72bbd9caca9648e0c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ajsfx-e4cbc88db4f7f4d72bbd9caca9648e0c av_two_third  avia-builder-el-54  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-10axl-36e45ff02f8e2886226f99ffd49fa7be '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><div id=\"u6124-4\" class=\"clearfix colelem shared_content\" data-content-guid=\"u6124-4_content\">\n<h2 id=\"u6124-2\">RACONTER L&rsquo;HISTOIRE DE L&rsquo;EFFECTIVIT\u00c9<\/h2>\n<\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-99qsx-ab69cd32f32a8d18ce585bf82c65ead0\">\n#top .hr.av-99qsx-ab69cd32f32a8d18ce585bf82c65ead0{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-99qsx-ab69cd32f32a8d18ce585bf82c65ead0 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-99qsx-ab69cd32f32a8d18ce585bf82c65ead0 hr-custom  avia-builder-el-56  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-8tm8x-6a6d223ff40fb2a64ac4acaaeb865280  avia-builder-el-57  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-98 avia-img-lazy-loading-not-98 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/charlie-snow.jpg\" alt='Charlie Snow'  itemprop=\"image\"   height=\"99\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/charliedosurf<\/span><a href='https:\/\/twitter.com\/charliedosurf' class='avia-team-icon av-86ctp-1fa40a57f6d7b58fb45df4b03f6cf830 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Charlie Snow<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Directeur Strat\u00e9gique, MullenLowe London<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-7fkh1-0b87d5ddea5595d92416964987871837 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>En tant que planificateur dans le monde des agences depuis plus de 20 ans, l&rsquo;une de mes responsabilit\u00e9s principales a \u00e9t\u00e9 de coordonner la mesure des campagnes et de dire aux gens ce qui a fonctionn\u00e9 (et ce qui n&rsquo;a pas fonctionn\u00e9) dans nos communications ; en int\u00e9grant cette information dans le processus de planification pour rendre les communications encore plus efficaces la prochaine fois. J&rsquo;ai aussi eu de nombreuses tentatives pour convaincre les gens de l&rsquo;efficacit\u00e9 de nos communications en r\u00e9digeant et en \u00e9ditant des papiers sur l&rsquo;efficacit\u00e9 pour divers prix.<\/p>\n<p>De l&rsquo;autre c\u00f4t\u00e9, j&rsquo;ai \u00e9galement assist\u00e9 \u00e0 de nombreuses pr\u00e9sentations et d\u00e9briefings, et j&rsquo;ai eu le grand privil\u00e8ge de juger des prix prestigieux sur l&rsquo;efficacit\u00e9 \u2013 \u00e9coutant ou lisant les arguments avanc\u00e9s.<\/p>\n<p>Tout cela m&rsquo;a convaincu d&rsquo;une chose : vous pouvez avoir toutes les donn\u00e9es du monde \u00e0 votre disposition, mais si vous ne pouvez pas livrer les preuves de mani\u00e8re claire, simple et convaincante, vous ne pourrez convaincre personne de l&rsquo;efficacit\u00e9. La fa\u00e7on dont vous le racontez est aussi importante, sinon plus, que ce que vous dites.<\/p>\n<p>Alors, quand vous essayez de convaincre les gens de l&rsquo;efficacit\u00e9 des communications, ne vous contentez pas d&rsquo;\u00e9crire un essai, soyez un raconteur d&rsquo;histoires.<\/p>\n<h4 id=\"u6160-10\">1. PLANIFIEZ L&rsquo;HISTOIRE<\/h4>\n<p>Les bonnes histoires ont un flux narratif solide. Je recommande vivement aux gens de commencer par le nouveau cadre interactif propos\u00e9 par AMEC \u2013 il peut fournir la structure simple pour votre histoire.<\/p>\n<p>L&rsquo;un des d\u00e9fauts les plus courants dans les papiers sur l&rsquo;efficacit\u00e9 est le \u00ab\u00a0lancer de donn\u00e9es\u00a0\u00bb \u2013 balancer toutes les statistiques d&rsquo;un coup, sans ordre particulier. Le cerveau humain a du mal \u00e0 assimiler ce genre d&rsquo;information facilement. Suivre le cadre vous permet de d\u00e9composer naturellement vos informations et vos donn\u00e9es en morceaux digestes.<\/p>\n<p>Cela demande un effort pour d\u00e9composer vos informations. \u00c0 premi\u00e8re vue, cela peut sembler assez d\u00e9routant de comprendre la diff\u00e9rence entre un \u00ab output \u00bb (retomb\u00e9e), un \u00ab out-take \u00bb (r\u00e9action) et un \u00ab outcome \u00bb (r\u00e9sultat). Mais ce n&rsquo;est vraiment pas si difficile si vous prenez un peu de temps pour le faire et suivez les d\u00e9finitions simples fournies.<\/p>\n<p>Le cadre vous permet de faire des connexions \u00e9tape par \u00e9tape entre vos communications, les changements d&rsquo;attitude et de comportement, et l&rsquo;effet commercial ou social. C&rsquo;est le plus grand d\u00e9fi de toute histoire d&rsquo;efficacit\u00e9 : \u00ab comment pouvez-vous prouver que c\u2019\u00e9taient les communications qui ont fait la diff\u00e9rence ? \u00bb Le cadre est con\u00e7u pour faciliter la visualisation de ces liens.<br \/>\nUne fois que vous avez les bases et le flux narratif, ajoutez un peu d&rsquo;\u00e9clat.<\/p>\n<h4 id=\"u6160-22\">\u00a02. AJOUTEZ UN PEU D&rsquo;\u00c9CLAT \u00c0 L&rsquo;HISTOIRE<\/h4>\n<p>Il s&rsquo;agit ici de rendre l&rsquo;histoire int\u00e9ressante et engageante, de la sortir du domaine de l&rsquo;information s\u00e8che.<\/p>\n<p>Donnez \u00e0 votre histoire un titre. Pour vous inspirer, regardez les meilleures \u00ab\u00a0TED Talks\u00a0\u00bb \u2013 beaucoup d&rsquo;entre elles ont un titre simple pour attirer votre attention ; un titre audacieux, inspirant, contre-intuitif \u2013 en tout cas, quelque chose de stimulant et provocateur qui vous donne envie d&rsquo;\u00e9couter ou de lire plus loin.<\/p>\n<p>\u00c0 partir de l\u00e0, r\u00e9duisez l&rsquo;histoire \u00e0 une version d&rsquo;une minute \u2013 l&rsquo;\u00e9quivalent de la couverture du livre qui vous donne envie de lire davantage ; soutenez-la avec une version \u00e9tendue de cinq minutes, qui couvre les points principaux de chaque section du cadre, et terminez avec la version compl\u00e8te de vingt minutes de l&rsquo;histoire. Ce processus vous oblige \u00e0 prioriser vos informations et vos donn\u00e9es \u00e0 chaque section. Quels sont les sorties, les r\u00e9actions et les r\u00e9sultats les plus impressionnants que vous avez ?<\/p>\n<p>Enfin, allez chercher l&rsquo;humanit\u00e9 et l&rsquo;\u00e9motion pour cr\u00e9er des connexions plus fortes avec l&rsquo;audience ou le lecteur ; \u00e9vitez le langage marketing \u00e9trange ou des th\u00e9ories trop complexes qui peuvent sembler intelligentes mais qui \u00e9loignent souvent les gens. Si vous parvenez \u00e0 avoir une structure narrative solide, puis \u00e0 ajouter un peu d&rsquo;\u00e9clat, votre histoire d&rsquo;efficacit\u00e9 sera bien racont\u00e9e, et deviendra bien plus convaincante et persuasive.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='conclusion'  class='avia-section av-6xe89-963444ef0738390e81d62ae1cf26a4b6 main_color avia-section-default avia-no-shadow  avia-builder-el-59  el_after_av_section  el_before_av_one_third  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6gtxl-a761b9d35b3bf1cbdbeda756133f0010\">\n.flex_column.av-6gtxl-a761b9d35b3bf1cbdbeda756133f0010{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-6gtxl-a761b9d35b3bf1cbdbeda756133f0010 av_one_third  avia-builder-el-60  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5r1rp-3cbb4c450032afad3a382b465dab670b\">\n.flex_column.av-5r1rp-3cbb4c450032afad3a382b465dab670b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5r1rp-3cbb4c450032afad3a382b465dab670b av_two_third  avia-builder-el-61  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-4vg1d-4877de7731acd10f43f6d09d9d77ac24 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><div id=\"u6124-4\" class=\"clearfix colelem shared_content\" data-content-guid=\"u6124-4_content\">\n<h2 id=\"u6253-2\">CONCLUSIONS:<\/h2>\n<h3 id=\"u6253-4\">MAINTENANT RACONTEZ VOTRE HISTOIRE DE MESURE<\/h3>\n<\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-49un9-5b18ff2552d7762beb8a0f63d47f1cf3\">\n#top .hr.av-49un9-5b18ff2552d7762beb8a0f63d47f1cf3{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-49un9-5b18ff2552d7762beb8a0f63d47f1cf3 .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-49un9-5b18ff2552d7762beb8a0f63d47f1cf3 hr-custom  avia-builder-el-63  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-3qii5-e2211a3b30ab687676f898900bdc8beb  avia-builder-el-64  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-96 avia-img-lazy-loading-not-96 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/elayne-phillips.jpg\" alt='Elayne Phillips'  itemprop=\"image\"   height=\"79\" width=\"99\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/layneyp<\/span><a href='https:\/\/twitter.com\/layneyp' class='avia-team-icon av-358x1-afc884883097dcf0fc7d513ce187f7e2 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Elayne Phillips<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Responsable de la communication du service civil et communication interne, Bureau du Premier ministre et Communications du Cabinet, et directrice du conseil d\u2019administration AMEC<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-2uoqx-fa917c452077f16282a7d6c3d1e09583 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>La mesure et l&rsquo;\u00e9valuation doivent r\u00e9v\u00e9ler une histoire, bas\u00e9e sur des preuves; elles doivent expliquer ce qui s&rsquo;est pass\u00e9, ce qui a fonctionn\u00e9, ce qui n&rsquo;a pas fonctionn\u00e9, et elles doivent conduire \u00e0 des enseignements exploitables. Il ne s&rsquo;agit pas simplement de collecter des chiffres, d&rsquo;enregistrer des donn\u00e9es et de faire des rapports \u2013 ensemble, elles doivent mettre en valeur :<\/p>\n<ul>\n<li>Ce que les r\u00e9sultats interm\u00e9diaires ont \u00e9t\u00e9 et quelles activit\u00e9s ont \u00e9t\u00e9 r\u00e9alis\u00e9es<\/li>\n<li>Ce que votre public cible a retenu de vos communications<\/li>\n<li>Et quel a \u00e9t\u00e9 le r\u00e9sultat final par rapport \u00e0 votre objectif.<\/li>\n<\/ul>\n<p>Tout cela devrait vous apprendre certaines choses, parfois en temps r\u00e9el, parfois apr\u00e8s coup lorsque vous regardez en arri\u00e8re, et parfois les deux. Apprendre quels canaux fonctionnent bien, quels messages g\u00e9n\u00e8rent le plus d&rsquo;engagement et quels partenariats produisent les meilleurs r\u00e9sultats devrait informer ce que vous faites ensuite, et finalement mener \u00e0 arr\u00eater certaines activit\u00e9s et en augmenter d&rsquo;autres.<\/p>\n<p>Pour apprendre de l&rsquo;analyse, vous devez \u00eatre compl\u00e8tement honn\u00eate sur les r\u00e9sultats. \u00c9vitez les indicateurs de vanit\u00e9 et rappelez-vous que plus l&rsquo;\u00e9valuation est significative, plus l&rsquo;histoire de la mesure sera cr\u00e9dible.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_9'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15280'><div class='entry-content-wrapper clearfix'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1xpk1-4071893329990a0e83ede6dd192c5ca2\">\n.flex_column.av-1xpk1-4071893329990a0e83ede6dd192c5ca2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1xpk1-4071893329990a0e83ede6dd192c5ca2 av_one_third  avia-builder-el-66  el_after_av_section  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1nkid-154ed07fec60efbd1f0aca637d9b38b9\">\n.flex_column.av-1nkid-154ed07fec60efbd1f0aca637d9b38b9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1nkid-154ed07fec60efbd1f0aca637d9b38b9 av_two_third  avia-builder-el-67  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ovcx-fca00870236949d45a98ad34b64dfaad\">\n#top .av_textblock_section.av-ovcx-fca00870236949d45a98ad34b64dfaad .avia_textblock{\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-ovcx-fca00870236949d45a98ad34b64dfaad '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p style=\"text-align: center;\"><a class=\"framework-button\" href=\"https:\/\/amec.blazedev.co.uk\/amecframework\/en\/interactive-framework\/\" target=\"_blank\" rel=\"noopener\">CLIQUEZ ICI POUR ACC\u00c9DER AU CADRE D&rsquo;\u00c9VALUATION INT\u00c9GR\u00c9.<\/a><\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":15223,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"class_list":["post-15280","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expert Opinion - AMEC Integrated Evaluation Framework<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expert Opinion - AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/\" \/>\n<meta property=\"og:site_name\" content=\"AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T13:07:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/expert-opinion\\\/\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/expert-opinion\\\/\",\"name\":\"Expert Opinion - AMEC Integrated Evaluation Framework\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\"},\"datePublished\":\"2016-08-15T11:49:57+00:00\",\"dateModified\":\"2025-01-20T13:07:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/expert-opinion\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/expert-opinion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/expert-opinion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Supporting Material\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/fr\\\/home\\\/supporting-material\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Expert Opinion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/\",\"name\":\"AMEC Integrated Evaluation Framework\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expert Opinion - AMEC Integrated Evaluation Framework","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Expert Opinion - AMEC Integrated Evaluation Framework","og_url":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/","og_site_name":"AMEC Integrated Evaluation Framework","article_modified_time":"2025-01-20T13:07:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/","name":"Expert Opinion - AMEC Integrated Evaluation Framework","isPartOf":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website"},"datePublished":"2016-08-15T11:49:57+00:00","dateModified":"2025-01-20T13:07:49+00:00","breadcrumb":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/expert-opinion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/home\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/"},{"@type":"ListItem","position":3,"name":"Supporting Material","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/home\/supporting-material\/"},{"@type":"ListItem","position":4,"name":"Expert Opinion"}]},{"@type":"WebSite","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/","name":"AMEC Integrated Evaluation Framework","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/pages\/15280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/comments?post=15280"}],"version-history":[{"count":4,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/pages\/15280\/revisions"}],"predecessor-version":[{"id":15297,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/pages\/15280\/revisions\/15297"}],"up":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/pages\/15223"}],"wp:attachment":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/media?parent=15280"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/fr\/wp-json\/wp\/v2\/tags?post=15280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}