{"id":436,"date":"2016-08-22T15:45:23","date_gmt":"2016-08-22T14:45:23","guid":{"rendered":"http:\/\/amecorg.com\/amecframework\/es\/?page_id=436"},"modified":"2024-11-25T16:41:39","modified_gmt":"2024-11-25T16:41:39","slug":"expert-opinion","status":"publish","type":"page","link":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/","title":{"rendered":"Opini\u00f3n experta"},"content":{"rendered":"<div class='clear'><\/div><div id='sub_menu1'  class='av-submenu-container av-av_submenu-ef373496a6e07cebc59c401e2071f3ce main_color  avia-builder-el-0  el_before_av_section  avia-builder-el-first  side-menu av-sticky-submenu container_wrap fullsize' style='z-index:301' ><div class='container av-menu-mobile-disabled av-submenu-pos-center'><ul id='av-custom-submenu-1' class='av-subnav-menu' role='menu'>\n<li class='menu-item av-av_submenu_item-6c89be25a66195fbb7034c2c11a3708c menu-item-top-level menu-item-top-level-1' role='menuitem'><a href='#proving-value'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Probando el valor en un mundo integrado<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-4835ff26c55dbf0aed4382993ee06ada menu-item-top-level menu-item-top-level-2' role='menuitem'><a href='#why-measurement-matters'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Por qu\u00e9 las mediciones cuentan<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-d220c45405bde002b5dd0bf19a5e4721 menu-item-top-level menu-item-top-level-3' role='menuitem'><a href='#the-pesco-channel'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Los canales del PESO<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-f20e71e9e0bba0e04d11d30c84aab2ab menu-item-top-level menu-item-top-level-4' role='menuitem'><a href='#performance-public-relations'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Actuaci\u00f3n, relaciones p\u00fablicas<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-991d93fbd524f104c91d7f6a4ac70881 menu-item-top-level menu-item-top-level-5' role='menuitem'><a href='#if-your-failing'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Si est\u00e1 fallando en planificar esta planificando fallar<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-cb3a631174d26fd161733fe6b6d42027 menu-item-top-level menu-item-top-level-6' role='menuitem'><a href='#top-tips'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Los mejores consejos para planificar y elegir blancos o metas<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-c40679c633903f94bd57a9f0be3812a3 menu-item-top-level menu-item-top-level-7' role='menuitem'><a href='#measuring-reputation'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Midiendo reputaciones<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-71bbe1fedc193267f19837482e381132 menu-item-top-level menu-item-top-level-8' role='menuitem'><a href='#effectiveness-story'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Diciendo la historia de la efectividad<\/span><\/a><\/li>\n<li class='menu-item av-av_submenu_item-243aec29971bbe0b0c340b9b210f4c9a menu-item-top-level menu-item-top-level-9' role='menuitem'><a href='#conclusion'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Conclusiones<\/span><\/a><\/li>\n<\/ul><\/div><\/div><div class='sticky_placeholder'><\/div>\n<div id='proving-value'  class='avia-section av-av_section-46420b1142f37fb7579555108e4e1361 main_color avia-section-default avia-no-shadow  avia-builder-el-1  el_after_av_submenu  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-2  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-3  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>PROBANDO EL VALOR EN UN MUNDO INTEGRADO<\/h2>\n<div id=\"u4637-6\" class=\"clearfix colelem shared_content\" data-content-guid=\"u4637-6_content\">\n<h3 id=\"u4637-4\">POR QU\u00c9 NECESITAMOS APARTARNOS DE SOLAMENTE MEDIR RESULTADOS<\/h3>\n<\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-5  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-eddae327d8e2c1ddc9572e1198908256  avia-builder-el-6  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-90 avia-img-lazy-loading-not-90 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1.jpg\" alt='Richard Bagnall'  itemprop=\"image\"   height=\"92\" width=\"92\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1.jpg 92w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1-80x80.jpg 80w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Richard-Bagnall-1-36x36.jpg 36w\" sizes=\"(max-width: 92px) 100vw, 92px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/richardbagnall<\/span><a href='https:\/\/twitter.com\/richardbagnall' class='avia-team-icon av-av_team_icon-ab87a77926b8f129fb63be138573226c twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'  target='_blank' data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Richard Bagnall<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Director de la junta AMEC,<br \/>\nPRIME Research UK<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u4634-2\">Hay una cantidad de razones por las cuales la industria necesita apartarse de un pasado enfocado en el an\u00e1lisis de contenido como un medio que sustituye la medici\u00f3n de actividades de comunicaci\u00f3n. Nos guste o no, vivimos en un mundo donde muchas de las m\u00e9tricas en las cuales confi\u00e1bamos en el pasado para medir la efectividad de la comunicaci\u00f3n est\u00e1n perdiendo su relevancia. El universo de los medios se est\u00e1 expandiendo en t\u00e9rminos de canales y medios, pero contray\u00e9ndose en t\u00e9rminos de p\u00fablico y atenci\u00f3n. Como los canales se fragmentan en pagos, compartidos, ganados, contar solo las viejas m\u00e9tricas de salida como volumen, impresiones y alcance en forma precisa y significativa se vuelve cada vez m\u00e1s dif\u00edcil.<\/p>\n<p id=\"u4634-4\">No solamente existe un desaf\u00edo en brindar informaci\u00f3n correcta de medios que en algunos casos guardan esta informaci\u00f3n como privada, pero en el mundo online muchos de los n\u00fameros devueltos son f\u00e1ciles de ganar y de trampear. Como resultado, vol\u00famenes e impresiones ya no son interpretados esencialmente como un \u00edndice. En la conferencia anual PR Noruega en marzo de 2016, hice una breve presentaci\u00f3n de 20 minutos en donde habl\u00e9 mas sobre este tema. Y no se preocupen, est\u00e1 en ingl\u00e9s.<\/p>\n<p id=\"u4634-6\">\n<\/div><\/section><br \/>\n<br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u4635-2\">Cuando estos cambios vienen juntos con la nueva realidad de un mundo integrado en donde se espera que las RR. PP. sean c\u00f3modas trabajando con medios pagos, compartidos y ganados, es claro que necesitamos pensar hacia adelante. Debemos movernos de la \u00fanica salida o producto b\u00e1sico para probar el valor de nuestros esfuerzos mirando las eliminaciones y resultados que derivan de nuestro trabajo.<\/p>\n<p id=\"u4635-4\">La estructura de Evaluaci\u00f3n Integrada de AMEC hace exactamente esto: construye un m\u00e9todo claro y f\u00e1cil de seguir para contar la historia de grandes RR. PP., desde objetivos apuntando al p\u00fablico, hasta planificaci\u00f3n de objetivos, actividades, resultados (salidas, eliminaciones, resultados) e impacto en los negocios. Solamente cuando el sector de RR. PP. trate de medir todo su efecto ser\u00e1 capaz de responder preguntas clave sobre la actuaci\u00f3n en noticias inteligibles y cre\u00edbles.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='why-measurement-matters'  class='avia-section av-av_section-47635f304a489258f79c325a01e02b2e main_color avia-section-default avia-no-shadow  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-11  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-12  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>POR QU\u00c9 LAS MEDICIONES IMPORTAN<\/h2>\n<h3>VISI\u00d3N DE LA AGENCIA GLOBAL DE RR. PP.<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-14  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-64a460c41323a0fb045d04f65f726c17  avia-builder-el-15  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-91 avia-img-lazy-loading-not-91 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team.jpg\" alt='Giles Peddy'  itemprop=\"image\"   height=\"79\" width=\"81\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team.jpg 81w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team-80x79.jpg 80w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/giles-peddy-meet-the-team-36x36.jpg 36w\" sizes=\"(max-width: 81px) 100vw, 81px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/GilesPeddy<\/span><a href='https:\/\/twitter.com\/GilesPeddy' class='avia-team-icon av-av_team_icon-6300a3b097d3a050f267f327e41db236 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Giles Peddy<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Director Gerente de Grupo<br \/>\nUK, LEWIS<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u5077-2\">Por muchos a\u00f1os, la palabra medici\u00f3n espantaba a los profesionales de la comunicaci\u00f3n. Hu\u00edan o se iban a tomar un trago. Casi lo puedo ver ahora. Revolviendo papeles, tosiendo y jugando con ese tornillo que no parece tener ninguna funci\u00f3n aparente en la silla. Cualquier cosa con tal de evadir la inc\u00f3moda verdad de que no hemos sido muy buenos en medici\u00f3n.<\/p>\n<p id=\"u5077-4\">Pero los vientos han ido cambiando en los \u00faltimos a\u00f1os. El creciente reconocimiento del valor estrat\u00e9gico de la comunicaci\u00f3n en la sala de reuniones, como as\u00ed tambi\u00e9n las crecientes demandas de justificar presupuestos que necesitan ser relacionados con el impacto en el negocio, han hecho que la comunicaci\u00f3n sea m\u00e1s importante.<\/p>\n<p id=\"u5077-6\">Sin embargo yo todav\u00eda argumentar\u00eda que la falta de procesamiento, metodolog\u00eda, est\u00e1ndares o una taxonom\u00eda clara de lo que constituye una buena medici\u00f3n han demorado a la industria. Este es especialmente el caso de las agencias que con frecuencia no realizan la tarea de medici\u00f3n y evaluaci\u00f3n (en colaboraci\u00f3n con terceros).<\/p>\n<p id=\"u5077-8\">Esta pobre adopci\u00f3n de una clara estructura de medici\u00f3n significa que en muchos casos las mediciones est\u00e1n enfocadas en los resultados y los productos de RR. PP. \u00bfPero qu\u00e9 pasa con los resultados de negocios? \u00bfDe qu\u00e9 manera una campa\u00f1a o actividad ha impactado en la percepci\u00f3n? \u00bfHa aumentado la recomendaci\u00f3n? \u00bfHa visto un cambio en la adopci\u00f3n de consumidores finales? \u00bfHa llevado a un aumento en la demanda por el producto o el servicio?<\/p>\n<p id=\"u5077-10\">Este nivel de medici\u00f3n todav\u00eda es una minor\u00eda (aunque est\u00e1 creciendo). Pero en mi opini\u00f3n y esta es una perspectiva de la agencia despu\u00e9s de todo, siempre debemos hacernos \u2014y lo que es m\u00e1s importante, contestarnos\u2014 una simple pregunta \u2013c\u00f3mo va este trabajo a ayudar en los negocios de los clientes?<\/p>\n<p id=\"u5077-12\">No importa cu\u00e1les sean los objetivos del negocio, eso es en lo que debemos enfocarnos y medir. Saber que es importante para el negocio quiere decir que estaremos mejor ubicados para construir una estructura m\u00e9trica relevante.<\/p>\n<p id=\"u5077-14\">Esta es la raz\u00f3n por la cual la Nueva Estructura de M\u00e9tricas V\u00e1lidas Interactivas de la Asociaci\u00f3n Internacional para la Medici\u00f3n y Evaluaci\u00f3n de Comunicaciones (AMEC) es tan vital para que las agencias (y los equipos del lado de los clientes) la adopten y utilicen. La nueva estructura interactiva les da a los usuarios una metodolog\u00eda y taxonom\u00eda clara para desarrollar un claro, medible plan de comunicaci\u00f3n, y evaluar su \u00e9xito. Les da a los usuarios de la herramienta un recorrido claro y lo que es m\u00e1s importante, un camino para demostrar el impacto en los negocios.<\/p>\n<p id=\"u5077-16\">Muchos dir\u00e1n que para mostrar el resultado de los negocios se necesita primero obtener informaci\u00f3n de muchas partes de la operaci\u00f3n. S\u00ed, as\u00ed es.. Pero al utilizar la herramienta interactiva por lo menos Ud. sabe lo que esas mediciones pueden ser, qui\u00e9n puede ser el due\u00f1o, y c\u00f3mo encajan en los esfuerzos de comunicaciones integradas que Ud. tan a menudo les dice a sus clientes que Ud. entrega.<\/p>\n<p id=\"u5077-18\">Y por esto los clientes necesitan mostrarnos informaci\u00f3n. Si tenemos acceso a la informaci\u00f3n, podemos medir nuestro trabajo de manera mucho m\u00e1s estrat\u00e9gica.<\/p>\n<p id=\"u5077-20\">Presenta oportunidades para profesionales h\u00e1biles para desenterrar nuevas percepciones que pueden informar una campa\u00f1a, cambiar la aproximaci\u00f3n y causar m\u00e1s impacto.\u00a0Por supuesto, a veces es dif\u00edcil mostrar lo que cada parte individual de la mezcla de mercadotecnia ha entregado, pero con mayor frecuencia, usar las herramientas apropiadas puede darle una buena idea. Al final, donde hay una estructura clara, hay un camino.<\/p>\n<p>As\u00ed pues, aunque la conversaci\u00f3n sobre mediciones puede parecer inc\u00f3moda para muchos, yo digo que no dejen que les incomode. P\u00f3nganlas al frente y en el centro y util\u00edcenlas para tener verdaderas conversaciones de negocios. Usen las nueva M\u00e9tricas V\u00e1lidas Interactivas AMEC como su br\u00fajula. Los vientos del cambio se han levantado. Ponga sus velas y avance hacia un nuevo mundo de mediciones.<\/p>\n<\/div><\/section><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='the-pesco-channel'  class='avia-section av-av_section-3be72f863e2b36d425ca0415e102a6d0 main_color avia-section-default avia-no-shadow  avia-builder-el-17  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-18  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-19  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 id=\"u5962-2\">LOS CANALES DEL PESO.<\/h2>\n<h3 id=\"u5962-4\">QU\u00c9 SON Y POR QU\u00c9 CUENTAN<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-21  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-8d6ad2ea9a818f6c73045a28e7aab3ea  avia-builder-el-22  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-93 avia-img-lazy-loading-not-93 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/gini-dietrich.jpg\" alt='Gini Dietrich'  itemprop=\"image\"   height=\"100\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/ginidietrich<\/span><a href='https:\/\/twitter.com\/ginidietrich' class='avia-team-icon av-av_team_icon-d10ed745c3308751fb9d78750ccab738 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Gini Dietrich<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>CEO<br \/>\nArment Dietrich Inc<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u5992-5\">Seg\u00fan <a href=\"http:\/\/www.biography.com\/people\/henry-ford-9298747\">Henry Ford<\/a>, \u201cJuntarse es un comienzo, permanecer juntos es progreso, trabajar juntos es \u00e9xito\u201d. Esto puede aplicarse a toda clase de entornos de trabajo, incluyendo firmas o departamentos de RR. PP., pero no es aplicable solamente a las organizaciones. Se lo puede aplicar tambi\u00e9n a una estrategia de comunicaci\u00f3n.<\/p>\n<p id=\"u5992-10\">Y es por esto que naci\u00f3 el <a href=\"http:\/\/spinsucks.com\/communication\/pr-pros-must-embrace-the-peso-model\/\">modelo PESO<\/a><a>. Represenos medios pagos, ganados, compartidos y propiedad de otros y necesita de una aproximaci\u00f3n integrada a las comunicaciones para que podamos medir nuestros esfuerzos a cosas que realmente les importan a las organizaciones como ser m\u00e1s clientes, mayores ingresos, mejores ganancias o nuevos donantes. Es hora de que nuestros esfuerzos sean vistos como una inversi\u00f3n versus un gasto, y el modelo PESO \u2014cuando se usa correctamente\u2014 lo llevar\u00e1 hasta all\u00ed.<\/a><\/p>\n<p id=\"u5992-12\">Contrario a una l\u00ednea de ensamblado. Ud. comenzar\u00e1 por el final, o con medios propiedad de otros. En el mundo actual, casi nada anda sin medios propiedad de otros en el centro de su programa de comunicaciones. Los periodistas quieren saber qu\u00e9 han publicado sus expertos en otras partes. Ud. no tiene nada que compartir en medios sociales si no tiene medios propiedad de otros.<\/p>\n<p id=\"u5992-14\">Ud. no tiene mucho para publicitar online si no tiene un contenido para promover. Y la mercadotecnia por e-mail se desploma si Ud. no comparte algo de valor. Es el centro de todo lo que Ud. hace y es imposible tener un programa integrado sin \u00e9l.<\/p>\n<p id=\"u5992-16\">Una vez que Ud. tenga una s\u00f3lida biblioteca de medios propiedad de otros, es hora de anunciarlo a todo el mundo. En 2016 esto quiere decir usar medios compartidos (redes sociales) para distribuci\u00f3n y promoci\u00f3n.<\/p>\n<p id=\"u5992-20\">Cada d\u00eda aparece una nueva red social y Ud. no tiene que estar en todas ellas. En realidad, \u00bfpor qu\u00e9 deber\u00eda Ud. estar en todas ellas? Haga su investigaci\u00f3n y establezca su presencia en aqu\u00e9llas que tienen sentido para sus metas.<\/p>\n<p id=\"u5992-22\">Estamos trabajando hacia atr\u00e1s, as\u00ed que los medios ganados deber\u00edan venir ahora, pero en realidad vienen a lo \u00faltimo. El nuevo canal en el cual nos enfocamos es los medios pagos, que es exactamente lo que significa. Aqu\u00ed est\u00e1 la oportunidad de ampliar su mensaje con propaganda y alcanzar nuevas audiencias por sumas tan peque\u00f1as como $5 por d\u00eda en cada plataforma. Facebook, LinkedIn, y Twitter tienen sus propias opciones de publicidad y a menudo ofrecen cupones a los primerizos, lo cual es todav\u00eda un incentivo m\u00e1s para probarlos. Ud. no quiere poner dinero en cada aviso, as\u00ed que pru\u00e9belo una vez por mes en cada plataforma. Hay, por supuesto, otras maneras de obtener amplificaci\u00f3n para sus medios propiedad de otros, como marketing por e-mail, blogging para invitados o contenido contribuido.<\/p>\n<p id=\"u5992-24\">Hablando de influenciadores, ahora es el momento de hablar sobre los medios ganados. No son extra\u00f1os para la comunicaci\u00f3n y las relaciones que Ud. gane son valiosas para la credibilidad de terceros.<\/p>\n<p id=\"u5992-28\">El poder del boca a boca no puede negarse, y es por eso que los medios ganados son una parte crucial para ganar autoridad. Estas relaciones llevan tiempo, confianza, y la debida diligencia. As\u00ed que puede ser que los medios ganados no den resultados inmediatos, pero una vez integrados con los otros medios, le dar\u00e1n resultados m\u00e1s r\u00e1pidamente que si se usan solos.<\/p>\n<p><a href=\"http:\/\/spinsucks.com\/communication\/pr-pros-must-embrace-the-peso-model\/\">El modelo PESO no es una estrategia de un talle que sirve para todos los tama\u00f1os, pero, como la l\u00ednea de montaje, requiere todos los canales trabajando<\/a> juntos para cosechar resultados de negocios.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='performance-public-relations'  class='avia-section av-av_section-fe7fde7c45b75a38db275c36861161b1 main_color avia-section-default avia-no-shadow  avia-builder-el-24  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-25  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-26  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\"><a href=\"http:\/\/spinsucks.com\/communication\/pr-pros-must-embrace-the-peso-model\/\">DESEMPE\u00d1O DE LAS RELACIONES P\u00daBLICAS <\/a><\/h2>\n<p id=\"u6003-4\">EXTRAYENDO INFORMACI\u00d3N DE LOS SILOS DENTRO DE SU ORGANIZACI\u00d3N ES CR\u00cdTICO PARA RELACIONES P\u00daBLICAS DE ALTO DESEMPE\u00d1O..<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-28  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-2d0e70c0a9bca5b708f5f41bc2959254  avia-builder-el-29  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-94 avia-img-lazy-loading-not-94 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington.jpg\" alt='Stephen Waddington'  itemprop=\"image\"   height=\"79\" width=\"79\" srcset=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington.jpg 79w, https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/stephen-waddington-36x36.jpg 36w\" sizes=\"(max-width: 79px) 100vw, 79px\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/wadds<\/span><a href='https:\/\/twitter.com\/wadds' class='avia-team-icon av-av_team_icon-40a70935f20bd856902cf7f9e44e7bb3 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Stephen Waddington<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Oficial Jefe de Enlistamiento<br \/>\nKetchum<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6033-2\">Existe la creencia en relaciones p\u00fablicas que la medici\u00f3n de nuestro trabajo es cara. La falta de presupuesto es a menudo citada como la raz\u00f3n de mediciones muy pobres.<\/p>\n<p id=\"u6033-4\">Pero el costo mayor para el desempe\u00f1o de su organizaci\u00f3n y su propio desarrollo es no medir el \u00e9xito de su trabajo.<\/p>\n<h4 id=\"u6033-6\">MIDA EL DESEMPE\u00d1O ORGANIZATIVO NO LOS MEDIOS<\/h4>\n<p id=\"u6033-8\">El negocio de las mediciones en las relaciones p\u00fablicas se construy\u00f3 sobre las m\u00e9tricas de medios tradicionales. Los cuales ya no sirven para este prop\u00f3sito, como mucho, representan una pobre aproximaci\u00f3n al desempe\u00f1o de los negocios.<\/p>\n<p id=\"u6033-10\">A medida que la pr\u00e1ctica se aleja de los medios tradicionales como forma primaria de la dedicaci\u00f3n a las relaciones p\u00fablicas a una variedad de medios sociales y digitales, el negocio se hace m\u00e1s listo para las mediciones.<\/p>\n<p id=\"u6033-12\">Nuestra oportunidad es definir s\u00f3lidos objetivos, resultados y producciones para una campa\u00f1a y entonces cubrir una estructura de medici\u00f3n y herramientas.<\/p>\n<p id=\"u6033-16\">Ahora tenemos acceso como nunca antes a fuentes de informaci\u00f3n y herramientas para medir resultados y producciones.<\/p>\n<h4 id=\"u6033-18\">EXTRAIGA INFORMACI\u00d3N DE LOS SILOS DEPARTAMENTALES<\/h4>\n<p id=\"u6033-20\">El desaf\u00edo es que esta informaci\u00f3n frecuentemente est\u00e1 enterrada en silos dentro de una organizaci\u00f3n. Presupuestos de departamento y demarcaciones pol\u00edticas tienen prioridad sobre demostraci\u00f3n del desempe\u00f1o.<\/p>\n<p id=\"u6033-22\">Yo le aconsejar\u00eda que se acerque a los silos dentro de su organizaci\u00f3n y excave la informaci\u00f3n. Las relaciones p\u00fablicas necesitan trabajar con el servicio al cliente, mercadotecnia y recursos humanos.<\/p>\n<p id=\"u6033-24\">Aqu\u00ed hay 30 lugares donde Ud. puede buscar informaci\u00f3n dentro de su organizaci\u00f3n como la base de una s\u00f3lida estructura de medici\u00f3n.<\/p>\n<h4 id=\"u6033-26\">RESULTADOS INTERMEDIOS<\/h4>\n<div id=\"u6033-96\" class=\"ts-Default-Link-Style--copy clearfix grpelem shared_content\" data-content-guid=\"u6033-96_content\">\n<ol id=\"u6033-87\" class=\"list0 nls-None\">\n<li id=\"u6033-28\">Art\u00edculo \u2013 volumen de art\u00edculos o publicidades catalogadas como de terceros. Relaci\u00f3n con resultados, \u00fatil para establecer bases comparando con una campa\u00f1a previa.<\/li>\n<li id=\"u6033-30\">Asistencia \u2013 consumidores o ciudadanos que est\u00e1n presentes en un evento como una conferencia, mesa redonda o reuniones p\u00fablicas.<\/li>\n<li id=\"u6033-32\">B\u00fasqueda de marca \u2013 aumento de actividad alrededor de una marca como resultado de actividad de relaciones p\u00fablicas.<\/li>\n<li id=\"u6033-34\">Conversaci\u00f3n \u2013 nexo con un resultado organizativo que de otra manera ser\u00eda una m\u00e9trica de vanidad, como mucho del negocio de medir medios sociales.<\/li>\n<li id=\"u6033-36\">Descarga \u2013 una forma de gu\u00eda que resulta de una llamada a la acci\u00f3n. Captura informaci\u00f3n para re-mercadeo o compromiso en actividad.<\/li>\n<li id=\"u6033-38\">Tiempo de estad\u00eda \u2013 tiempo pasado en una p\u00e1gina web. \u00datil para distinguir entre tr\u00e1fico normal y si un visitante ha le\u00eddo el contenido de la p\u00e1gina.<\/li>\n<li id=\"u6033-40\">Clic de e-mail recibido \u2013 se usa para determinar si un recibidor de e-mail ha recibido y ha reaccionado a una llamada a la acci\u00f3n.<\/li>\n<li id=\"u6033-42\">Seguidores \u2013 construyendo una audiencia o p\u00fablico como parte de una comunidad marcada. La tasa de crecimiento es tambi\u00e9n un indicador \u00fatil.<\/li>\n<li id=\"u6033-44\">Hits o vistas \u2013 un indicador de una visita a una p\u00e1gina web pero ojo con el tr\u00e1fico falso o irrelevante. \u00daselo en comunicaciones en conjunci\u00f3n con tiempo de estad\u00eda como indicador de un real compromiso.<\/li>\n<li id=\"u6033-46\">Nexos sujetos \u2013 calidad y volumen de los nexos atados a un URL predeterminado. Relacionado con el tr\u00e1fico. Con frecuencia usado en campa\u00f1as de b\u00fasqueda.<\/li>\n<li id=\"u6033-48\">Gustar \u2013 frecuentemente esto es una m\u00e9trica de vanidad de los medios sociales pero \u00fatil como indicador si hay una correlaci\u00f3n con otro intermediario o con un resultado organizativo.<\/li>\n<li id=\"u6033-50\">Tr\u00e1fico de referencia \u2013 tr\u00e1fico de sitios web de terceros, t\u00edpicamente usados aguas abajo en conjunci\u00f3n con nexos atados.<\/li>\n<li id=\"u6033-52\">Revisiones \u2013 una forma de validaci\u00f3n de terceros que se est\u00e1 abriendo paso de los sectores de hospitalidad y viajes hacia otras industrias.<\/li>\n<li id=\"u6033-54\">Sentimiento \u2013 bueno o malo es usualmente todo lo que Ud. necesita saber a menos que Ud. est\u00e9 trabajando en o moviendo opiniones acerca de un tema durante un cierto per\u00edodo de tiempo.<\/li>\n<li id=\"u6033-56\">Voz compartida \u2013 volumen de conversaci\u00f3n en medios sociales o tradicionales para una organizaci\u00f3n vs. una organizaci\u00f3n de la competencia.<\/li>\n<li id=\"u6033-58\">Compartiendo volumen \u2013 tasa de compartir en medios sociales a trav\u00e9s de canales diferentes. Conecta canales a conducta y resultados.<\/li>\n<li id=\"u6033-60\">B\u00fasqueda no marcada \u2013 empuj\u00f3n o contribuci\u00f3n a la actividad de b\u00fasqueda alrededor de un t\u00e9rmino como resultado de la actividad de las relaciones p\u00fablicas.<\/li>\n<li id=\"u6033-62\">Pisada \u2013 cu\u00e1nta gente ha viajado hasta o visitado un lugar, usado frecuentemente en viajes, turismo y hospitalidad.<\/li>\n<\/ol>\n<div id=\"pu6033-96\" class=\"clearfix colelem\">\n<div id=\"u6038-4\" class=\"ts-Default-Link-Style--copy clearfix grpelem shared_content\" data-content-guid=\"u6038-4_content\">\n<p id=\"u6038-2\"><strong>LOS RESULTADOS ORGANIZATIVOS<\/strong><\/p>\n<\/div>\n<\/div>\n<ol id=\"u6033-87\" class=\"list0 nls-None\" style=\"counter-reset: section;\">\n<li id=\"u6033-64\">Cambio de actitud \u2013 una variedad de t\u00e9cnicas antes y despu\u00e9s de una encuesta usadas para chequear un cambio de opini\u00f3n. Popular en encuestas pol\u00edticas.<\/li>\n<li id=\"u6033-66\">Conciencia \u2013 compromiso de un p\u00fablico que de otra manera no hubiera sido consciente de un tema, producto o servicio. Probado a trav\u00e9s de una variedad de t\u00e9cnicas de encuesta.<\/li>\n<li id=\"u6033-68\">Cambios de conducta \u2013 Mejoras sociales, econ\u00f3micas como disminuciones en conductas antisociales probadas a trav\u00e9s de seguimiento longitudinal.<\/li>\n<li id=\"u6033-70\">Proceso de negocios \u2013 mejora en la productividad t\u00edpicamente debida a comunicaciones internas y entrenamiento.<\/li>\n<li id=\"u6033-72\">Conversiones \u2013 t\u00edpicamente ventas, pero tambi\u00e9n se aplica a otras actividades organizativas, que pueden ser atribuidas a la actividad de las relaciones p\u00fablicas.<\/li>\n<li id=\"u6033-74\">Desempe\u00f1o financiero \u2013 sigue el rastro del rol de las relaciones p\u00fablicas cuando apoya una m\u00e9trica financiera como precio compartido o valuaci\u00f3n.<\/li>\n<li id=\"u6033-76\">Internas \u2013 una serie de m\u00e9tricas que incluyen reclutamiento mejorado, retenci\u00f3n y productividad y disminuci\u00f3n de ausencias y enfermedades.<\/li>\n<li id=\"u6033-78\">Recomendaci\u00f3n y referencias \u2013 la base del Promotor de Red, que prueba la factibilidad de una recomendaci\u00f3n de terceros o referencia (vea tambi\u00e9n satisfacci\u00f3n).<\/li>\n<li id=\"u6033-80\">Retenci\u00f3n \u2013 se aplica a clientes o personal cuando las relaciones p\u00fablicas est\u00e1n enfocadas en el manejo de las relacione.<\/li>\n<li id=\"u6033-82\">Satisfacci\u00f3n \u2013 relacionada con recomendaci\u00f3n, usada para marcar la fuerza b\u00e1sica de una relaci\u00f3n entre un ciudadano o un consumidor y una organizaci\u00f3n.<\/li>\n<li id=\"u6033-84\">Disparadores \u00fanicos \u2013 cupones regalados, n\u00fameros de tel\u00e9fono o URL que chequean la relaci\u00f3n entre actividad y resultados.<\/li>\n<li id=\"u6033-86\">Votos \u2013 la cruda realidad de las campa\u00f1as pol\u00edticas donde la prueba final del \u00e9xito de la campa\u00f1a es en el cuarto de votos.<\/li>\n<\/ol>\n<\/div>\n<ol id=\"u6033-87\" class=\"list0 nls-None\"><\/ol>\n<h4 id=\"u6033-89\">ACERCA DE STEPHEN WADDINGTON<\/h4>\n<p id=\"u6033-94\"><span id=\"u6033-91\">Stephen es un socio y Oficial Jefe de enlistamiento en Ketchum. Es Profesor Visitante en la Universidad de Newcastle. Bloguea en\u00a0<a class=\"nonblock\" href=\"http:\/\/wadds.co.uk\/\" target=\"_blank\" rel=\"noopener\">wadds.co.uk<\/a><\/span>.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='if-your-failing'  class='avia-section av-av_section-c5d0737d0295b6a4d8d40c19790e866d main_color avia-section-default avia-no-shadow  avia-builder-el-31  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-32  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-33  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\">\u201dSI UD ESTA FALLANDO EN SU PLAN ESTA PLANEANDO FALLAR\u201d<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-35  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-f86215e6061eabd8f51cca8e8e45b803  avia-builder-el-36  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-95 avia-img-lazy-loading-not-95 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/Kevin-read.jpg\" alt='Kevin Read'  itemprop=\"image\"   height=\"95\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/readkevinread<\/span><a href='https:\/\/twitter.com\/readkevinread' class='avia-team-icon av-av_team_icon-2bcc0ed4322a3fde8382bda7a6a001fe twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Kevin Read<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Miembro del Directorio &<br \/>\nSocior, Bell Pottinger<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6043-2\">La nueva estructura de m\u00e9tricas de AMEC es un trabajo formidable que sujeta un pensamiento poderoso, relevante y utilizable en una forma pr\u00e1ctica y f\u00e1cil de seguir.<\/p>\n<p id=\"u6043-4\">Parar Bell Pottinger, uno de los m\u00e1s nuevos miembros de AMEC, es particularmente \u00fatil en desplegar un camino que nuestros consultores pueden seguir. Es de ayuda para conversaciones con los clientes acerca de c\u00f3mo establecer un plan e informar sobre la validez de las campa\u00f1as.<\/p>\n<p id=\"u6043-6\">Con la llegada de canales digitales y sociales como canales de la corriente principal la complejidad de muchas de las campa\u00f1as que llevamos a cabo ha aumentado dram\u00e1ticamente. Esto no solamente significa que necesitamos entender c\u00f3mo medir impactos a trav\u00e9s de un rango m\u00e1s amplio de canales de distribuci\u00f3n pero tambi\u00e9n tenemos que ser m\u00e1s conscientes de las consecuencias de m\u00faltiples puntos de contacto.<\/p>\n<p id=\"u6043-8\">Igualmente, la estructura contin\u00faa colocando un \u00e9nfasis considerable en comprender el contenido y la estrategia del negocio que se halla detr\u00e1s de las campa\u00f1as modernas. Planificando por objetivos organizativos clara y met\u00f3dicamente antes de cualquier actividad es esencial para el \u00e9xito.<\/p>\n<p id=\"u6043-10\">En consultor\u00edas con una fuerte pr\u00e1ctica en aconsejar se pone \u00e9nfasis en nuestros socios y en consultores que tiene un profundo conocimiento de los negocios de sus clientes y de los sectores en los que operan. Estos conocimientos a menudo vienen de una interrogaci\u00f3n consciente de los objetivos amplios de una organizaci\u00f3n y el contexto en el cual han sigo formulados.<\/p>\n<p id=\"u6043-12\">Anal\u00edticos que se enfocan en las diferentes aproximaciones son tambi\u00e9n de ayuda. Entendiendo c\u00f3mo las actividades pagas, propiedad de otros y compartidas act\u00faan en relaci\u00f3n unas con otras le da al planificador de comunicaciones una visi\u00f3n m\u00e1s comprehensiva de las sinergias de canales potenciales.<\/p>\n<p id=\"u6043-14\">En equipos h\u00edbridos, con diferentes agencias representadas en ellos puede haber a veces desaf\u00edos considerables en juntar toda la informaci\u00f3n de planificaci\u00f3n relevante. Atrapando resultados de multicanales puede tambi\u00e9n ser dif\u00edcil.<\/p>\n<p id=\"u6043-16\">El foco continuo cuando se miran las reacciones iniciales de una audiencia a las comunicaciones los efectos subsecuentes y el impacto a largo plazo son un modelo s\u00f3lido y fuerte con los cuales las consultor\u00edas podr\u00e1n trabajar. El arte con este modelo es siempre ser l\u00edmpido como el cristal cerca de qu\u00e9 m\u00e9tricas o hitos Ud. est\u00e1 tratando de medir.<\/p>\n<p id=\"u6043-18\">A\u00fan es necesario ser cauteloso acerca de la causalidad, sin embargo es alentador ver que los impactos a largo plazo est\u00e1n firmemente enfocados en reputaci\u00f3n, relaciones y cambio.<\/p>\n<p id=\"u6043-20\">En Bell Pottinger recomendamos con confianza la nueva estructura de AMEC a socios y consultores en el negocio.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='top-tips'  class='avia-section av-av_section-c75e6b0d80ae33e2cd6e1e947c6872c8 main_color avia-section-default avia-no-shadow  avia-builder-el-38  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-39  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-40  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u5962-2\">CONSEJOS TOP PARA PLANIFICAR Y PONER METAS<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-42  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-d0fde122514a1cc6041bae95ec1c9910  avia-builder-el-43  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-96 avia-img-lazy-loading-not-96 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/elayne-phillips.jpg\" alt='Elayne Phillips'  itemprop=\"image\"   height=\"79\" width=\"99\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/layneyp<\/span><a href='https:\/\/twitter.com\/layneyp' class='avia-team-icon av-av_team_icon-72bd1695dee85cacc2f1c2d98c624d5d twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Elayne Phillips<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Jefa de Civil Service Comms & Internal Comms,<br \/>\nOficina del Primer Ministro & Cabinet Office Comms,<br \/>\n y miembro del directorio de r AMEC<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 id=\"u6166-2\">LA IMPORTANCIA DE PLANEAR Y PONER METAS<\/h4>\n<p id=\"u6166-4\">Buenas mediciones y evaluaci\u00f3n pueden revelar pensamientos que nos informan lo que Ud. har\u00e1 despu\u00e9s, hallazgos que pueden alterar la direcci\u00f3n de su campa\u00f1a e influenciar los canales que Ud. eligi\u00f3 para invertir esfuerzos en el futuro y los que no eligi\u00f3.<\/p>\n<p id=\"u6166-6\">Para maximizar los beneficios de la evaluaci\u00f3n de la comunicaci\u00f3n, la clave es hacer un plan. Lo antes posible, planee lo que Ud. va a medir, acord\u00e1ndose de medir lo que importa para sus objetivos, y ponga en marcha los mecanismos para empezar a seguir el rastro de las m\u00e9tricas correctas. Esto es importante por una cantidad de razones.<\/p>\n<p id=\"u6166-8\">Si Ud. no identifica al instante lo que es importante de seguir, puede encontrarse m\u00e1s tarde que es imposible encontrar retrospectivamente la fuente de la informaci\u00f3n que Ud. necesita.<\/p>\n<p id=\"u6166-10\">Planificar sus actividades de medici\u00f3n significar\u00e1 que Ud. no perder\u00e1 tiempo siguiendo el rastro de m\u00e9tricas in\u00fatiles o, peor a\u00fan, m\u00e9tricas de vanidad.<\/p>\n<p id=\"u6166-12\">Los planes de comunicaciones son m\u00e1s cre\u00edbles cuando pueden demostrar c\u00f3mo se ver\u00e1 el \u00e9xito y c\u00f3mo esto ser\u00e1 probado.<\/p>\n<p id=\"u6166-14\">Utilice siempre percepciones que vienen de evaluaciones previas, cuando sea relevante para su pr\u00f3xima campa\u00f1a para ayudar a poner metas. En la etapa de planificaci\u00f3n poner metas le dar\u00e1 un foco y ayudar\u00e1 a mantener el progreso de las mediciones en camino. As\u00ed pues, piense con cuidado, ponga metas y trace las medidas correctas de desempe\u00f1o desde el principio de su actividad.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='measuring-reputation'  class='avia-section av-av_section-1ffac49738274931de4f48b3ac7ad8fd main_color avia-section-default avia-no-shadow  avia-builder-el-45  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-46  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-47  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><h2 id=\"u6089-2\">MIDIENDO LA REPUTACI\u00d3N<\/h2>\n<h3>PREFACIO A LA MEDICI\u00d3N DE LA REPUTACI\u00d3N. USANDO LA REPUTACI\u00d3N PARA CREAR VALOR<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-49  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-5b8e7910b1ff1efbe2adffca109ba77b  avia-builder-el-50  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-97 avia-img-lazy-loading-not-97 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/prof-kevin-money.jpg\" alt='Kevin Money'  itemprop=\"image\"   height=\"110\" width=\"79\" \/><\/div><h3 class='team-member-name '  itemprop=\"name\" >Kevin Money<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Profesor de Reputation & Responsible Leadership,<br \/>\nHenley Business School<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6119-2\">La protecci\u00f3n y el resaltado de la reputaci\u00f3n son metas y objetivos frecuentes cuando la comunicaci\u00f3n es solicitada para apoyo. La nueva estructura integrada de AMEC deja en claro la importancia de la reputaci\u00f3n en medici\u00f3n. \u00bfPero c\u00f3mo puede Ud. medirla significativamente? \u00bfC\u00f3mo se conecta la reputaci\u00f3n con otros criterios de desempe\u00f1o, como tablas de ligas, y los rankings m\u00e1s admirados? \u00bfC\u00f3mo puede Ud. decir si su reputaci\u00f3n le est\u00e1 ayudando o est\u00e1 dificultando su organizaci\u00f3n a llegar a sus metas? \u00bfC\u00f3mo puede Ud. usar la medici\u00f3n de la reputaci\u00f3n para guiar la estrategia de su organizaci\u00f3n? \u00bfC\u00f3mo puede Ud. demostrar que la reputaci\u00f3n le est\u00e1 agregando valor a agentes importantes? \u00bfC\u00f3mo se comparan diferentes modelos de medici\u00f3n de reputaci\u00f3n? \u00bfC\u00f3mo se pueden combinar diferentes modelos de reputaci\u00f3n para crear percepciones que puedan ser llevadas a cabo? \u00bfY c\u00f3mo puede Ud. balancear informaci\u00f3n existente en su organizaci\u00f3n para demostrar y mejorar su reputaci\u00f3n?<\/p>\n<p id=\"u6119-4\">En su art\u00edculo de clase magistral el Profesor Kevin Money de la Henley Business School contesta estas preguntas presentando reputaci\u00f3n en un modelo de creaci\u00f3n de valor. Esta aproximaci\u00f3n pr\u00e1ctica le permitir\u00e1 a Ud. comparar sus m\u00e9todos actuales con las mejores pr\u00e1cticas. Tambi\u00e9n le permitir\u00e1 identificar ambas causas y consecuencias de la reputaci\u00f3n \u2014y de esta manera\u2014 puede ayudar a guiar la actividad organizativa y las futuras iniciativas de medici\u00f3n.<\/p>\n<p id=\"u6119-6\">Richard Bagnall y Professor Kevin Money, Junio, 2016<\/p>\n<p id=\"u6119-10\"><a class=\"nonblock\" href=\"http:\/\/www.henley.reading.ac.uk\/web\/FILES\/corporate\/cl-White_Paper_Reputation_K_Money_C_Hillenbrand.pdf\" target=\"_blank\" rel=\"noopener\"><span id=\"u6119-8\">Cliquee aqu\u00ed para leer M\u00e1s all\u00e1 de la medici\u00f3n de la reputaci\u00f3n: Usando la reputaci\u00f3n para Crear Valor de documento.<\/span><\/a><\/p>\n<p id=\"u6119-12\">Kevin Money y Carola Hillenbrand<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='effectiveness-story'  class='avia-section av-av_section-b923d734f7797d4a848d7760998bd4a5 main_color avia-section-default avia-no-shadow  avia-builder-el-52  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-53  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-54  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><div id=\"u6124-4\" class=\"clearfix colelem shared_content\" data-content-guid=\"u6124-4_content\">\n<h2 id=\"u6124-2\">CONTAR LA HISTORIA DE LA EFECTIVIDAD<\/h2>\n<\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-56  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-8de1de3c4e99af416528b349b7d1e799  avia-builder-el-57  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-98 avia-img-lazy-loading-not-98 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/charlie-snow.jpg\" alt='Charlie Snow'  itemprop=\"image\"   height=\"99\" width=\"79\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/charliedosurf<\/span><a href='https:\/\/twitter.com\/charliedosurf' class='avia-team-icon av-av_team_icon-9a0c04e3ea6b2834371e9748d581c289 twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Charlie Snow<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Oficial en Jefe de Estrategia, MullenLowe London<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6160-2\">Como planificador en un mundo de agencias por m\u00e1s de 20 a\u00f1os, una de mis principales responsabilidades ha sido conducir la medici\u00f3n de campa\u00f1as, y decirle a la gente qu\u00e9 result\u00f3 y qu\u00e9 no en nuestras comunicaciones. Ingresando esa informaci\u00f3n en el proceso de planificaci\u00f3n para hacer a\u00fan m\u00e1s efectivas las comunicaciones la pr\u00f3xima vez, he tenido muchos intentos de convencer a la gente de cu\u00e1n exitosa eran las comunicaciones de nuestra agencia escribiendo o editando una cantidad de papeles sobre efectividad, que ganaron premios.<\/p>\n<p id=\"u6160-4\">Como contraparte, he estado en muchas presentaciones y reuniones informativas y tuve el gran privilegio de juzgar prestigiosos premios de efectividad, escuchando o leyendo los argumentos presentados.<\/p>\n<p id=\"u6160-6\">Todo lo cual me ha convencido de una cosa sobre todo lo dem\u00e1s: Ud. puede tener toda la informaci\u00f3n del mundo a su alcance pero si Ud. no puede hacer conocer la evidencia en una forma simple, clara y atrapante. Ud. no podr\u00e1 convencer a nadie de la efectividad. La forma de decirlo es tan importante, si no m\u00e1s importante. que lo que Ud. dice<\/p>\n<p id=\"u6160-8\">As\u00ed que, cuando trate de convencer a la gente de la efectividad de las comunicaciones, no sea simplemente un escritor de ensayos, sea un contador de cuentos.<\/p>\n<h4 id=\"u6160-10\">1. PLANIFIQUE LA HISTORIA<\/h4>\n<p id=\"u6160-12\">Las buenas historias tienen una fuerte l\u00ednea narrativa. Recomiendo calurosamente a la gente comenzar con la nueva estructura interactiva propuesta por AMEC: puede darle una estructura simple para su cuento.<\/p>\n<p id=\"u6160-14\">Uno de los defectos m\u00e1s comunes en los papeles sobre efectividad es el \u201carrojar informaci\u00f3n \u201c \u2014lanzando todos los pensamientos en mont\u00f3n de una vez\u2014, sin un orden espec\u00edfico. La mente humana encuentra dif\u00edcil absorber esta clase de informaci\u00f3n con facilidad. Seguir la estructura le asegura que Ud. colocar\u00e1 la informaci\u00f3n y los datos en cantidades digeribles.<\/p>\n<p id=\"u6160-16\">Lleva esfuerzo desmenuzar la informaci\u00f3n. Aparentemente, puede ser muy confuso discernir la diferencia entre una \u201cproducci\u00f3n\u201d, una \u201celiminaci\u00f3n\u201d y un \u201cresultado\u201d. Pero no es realmente tan dif\u00edcil cuando Ud. le dedica un poco de tiempo y sigue las definiciones simples provistas.<\/p>\n<p id=\"u6160-18\">La estructura le permite a Ud. hacer conexiones paso a paso entre sus comunicaciones, cambio de conducta y de actitud, y el efecto social o comercial. Este es el desaf\u00edo m\u00e1s grande para cualquier historia de efectividad \u201c\u00bfc\u00f3mo puede Ud. probar que las comunicaciones lo hicieron?\u201d. La estructura fue dise\u00f1ada para hacer m\u00e1s f\u00e1cil ver los nexos.<\/p>\n<p id=\"u6160-20\">Una vez que Ud. tenga sus bases, y el relato fluya, entonces agr\u00e9guele algo de chispa.<\/p>\n<h4 id=\"u6160-22\">\u00a02. AGREGUE ALGO DE CHISPA A LA HISTORIA<\/h4>\n<p id=\"u6160-24\">Esto es todo sobre hacer la historia interesante y atrapante, llev\u00e1ndola por encima de un nivel de \u00e1rida informaci\u00f3n.<\/p>\n<p id=\"u6160-26\">Dele un t\u00edtulo a su historia. Para inspirarse, mire las mejores charlas \u201cTED\u201d \u2014muchas de ellas tienen un encabezado simple que atrapa la atenci\u00f3n, un encabezado que puede ser atrevido, inspirativo, contra intuitivo\u2014, lo que Ud. prefiera, es algo estimulante, provocante que hace que su mente siga escuchando o leyendo.<\/p>\n<p id=\"u6160-28\">De ah\u00ed en m\u00e1s, llegue a una versi\u00f3n m\u00e1s peque\u00f1a de la historia: el equivalente a la funda de un libro que hace que Ud. quiera leer m\u00e1s; ap\u00f3yela con una versi\u00f3n de cinco minutos con los titulares de cada secci\u00f3n de la estructura y termine con la versi\u00f3n de veinte minutos de la historia. Este proceso lo fuerza a uno a sentar prioridades en la informaci\u00f3n y datos de cada secci\u00f3n. \u00bfCu\u00e1l es el resultado, producci\u00f3n y conclusi\u00f3n m\u00e1s impresionante, que tiene Ud.?<\/p>\n<p id=\"u6160-30\">Y finalmente vaya tras lo humano y la emoci\u00f3n para hacer conexiones m\u00e1s fuertes con la audiencia, o lectores, evite un idioma raro de mercadotecnia o teor\u00edas demasiado complejas que pueden sonar inteligentes pero que a menudo alejan a la gente.<\/p>\n<p id=\"u6160-32\">Si Ud. puede lograr una s\u00f3lida estructura narrativa y luego agregarle algo de chispa su historia de efectividad puede ser bien narrada y ser mucho m\u00e1s atrapante y persuasiva como resultado.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='conclusion'  class='avia-section av-av_section-9d6ef0bbb1e4f746fe40705d3be7ccfd main_color avia-section-default avia-no-shadow  avia-builder-el-59  el_after_av_section  el_before_av_one_third  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-60  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_two_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-0aa7055fe62c3622faec82866afbaeb2 av_two_third  avia-builder-el-61  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-e4c4518831caa9edbdca90b100cd9b37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock performance-public-relations'  itemprop=\"text\" ><div id=\"u6124-4\" class=\"clearfix colelem shared_content\" data-content-guid=\"u6124-4_content\">\n<h2 id=\"u6253-2\">CONCLUSIONES<\/h2>\n<h3 id=\"u6253-4\">AHORA CUENTE SU HISTORIA DE MEDICIONES<\/h3>\n<\/div>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe\">\n#top .hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-05e93817e7a2f7c1e8c77a3a3c3fc4fe hr-custom  avia-builder-el-63  el_after_av_textblock  el_before_av_team_member  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='avia-team-member av-av_team_member-5b76ad70ea260774cfcb92add20956ae  avia-builder-el-64  el_after_av_hr  el_before_av_textblock '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class=\"team-img-container\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-96 avia-img-lazy-loading-not-96 avia_image avia_image_team' src=\"https:\/\/amec.blazedev.co.uk\/amecframework\/wp-content\/uploads\/2016\/08\/elayne-phillips.jpg\" alt='Elayne Phillips'  itemprop=\"image\"   height=\"79\" width=\"99\" \/><div class=\"team-social\"><div class=\"team-social-inner\"><span class='hidden av_member_url_markup twitter'  itemprop=\"url\" >https:\/\/twitter.com\/layneyp<\/span><a href='https:\/\/twitter.com\/layneyp' class='avia-team-icon av-av_team_icon-72bd1695dee85cacc2f1c2d98c624d5d twitter avia-iconfont avia-font-entypo-fontello' rel='v:url'   data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' ><\/a><\/div><\/div><\/div><h3 class='team-member-name '  itemprop=\"name\" >Elayne Phillips<\/h3><div class='team-member-description '  itemprop=\"description\" ><p>Jefa de Civil Service Comms & Internal Comms,<br \/>\nOficina del Primer Ministro & Cabinet Office Comms,<br \/>\ny Directora del Consejo de AMEC<\/p>\n<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >AMEC Integrated Evaluation Framework<\/span><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6283-2\">Medici\u00f3n y evaluaci\u00f3n deben revelar una historia basada en evidencia, deben explicar lo que sucedi\u00f3, qu\u00e9 result\u00f3 y qu\u00e9 no y deber\u00eda llevar a percepciones accionables. No es simplemente recoger n\u00fameros, guardar informaci\u00f3n, e informar, combinados deben mostrar.<\/p>\n<ul id=\"u6283-9\" class=\"list0 nls-None\">\n<li id=\"u6283-4\">C\u00f3mo han sido los resultados y qu\u00e9 actividades Ud. llev\u00f3 a cabo<\/li>\n<li id=\"u6283-6\">lo que su audiencia objetivo sac\u00f3 de sus comunicaciones<\/li>\n<li id=\"u6283-8\">y cu\u00e1l fue el resultado para su objetivo.<\/li>\n<\/ul>\n<p id=\"u6283-11\">Todo esto deber\u00eda ense\u00f1arle a Ud. varias cosas, a veces en tiempo real, a veces despu\u00e9s cuando Ud. mira para atr\u00e1s, y a veces ambas. Aprender de aquellos canales que est\u00e1n trabajando bien, qu\u00e9 mensajes est\u00e1n logrando m\u00e1s compromisos y qu\u00e9 asociados est\u00e1n produciendo los mejores resultados deber\u00eda informarle qu\u00e9 hacer despu\u00e9s y por \u00faltimo llevar al cese de algunas actividades e incrementar otras.<\/p>\n<p id=\"u6283-13\">Para aprender de los an\u00e1lisis debe Ud. ser totalmente honesto sobre sus hallazgos. Evite usar m\u00e9tricas de vanidad y recuerde que cuanto m\u00e1s significativa la evaluaci\u00f3n, m\u00e1s cre\u00edble ser\u00e1 la historia de la medici\u00f3n.<\/p>\n<\/div><\/section><\/p><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_9'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-436'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-9d24124a545ef7691702bdbb54c0e581\">\n.flex_column.av-av_one_third-9d24124a545ef7691702bdbb54c0e581{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-9d24124a545ef7691702bdbb54c0e581 av_one_third  avia-builder-el-66  el_after_av_section  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-96b8b3e4602814b30fda83b599dc53bd\">\n.flex_column.av-av_two_third-96b8b3e4602814b30fda83b599dc53bd{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-96b8b3e4602814b30fda83b599dc53bd av_two_third  avia-builder-el-67  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-e8931f3a3cb0ffe4e01460315f0ed18b\">\n#top .av_textblock_section.av-av_textblock-e8931f3a3cb0ffe4e01460315f0ed18b .avia_textblock{\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-e8931f3a3cb0ffe4e01460315f0ed18b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p style=\"text-align: center;\"><a class=\"framework-button\" href=\"https:\/\/amec.blazedev.co.uk\/amecframework\/en\/interactive-framework\/\" target=\"_blank\" rel=\"noopener\">Cliquee aqu\u00ed para acceder a la estructura integrada de evaluaci\u00f3n<\/a><\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":565,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"class_list":["post-436","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opini\u00f3n experta - AMEC Integrated Evaluation Framework<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opini\u00f3n experta - AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/\" \/>\n<meta property=\"og:site_name\" content=\"AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T16:41:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/expert-opinion\\\/\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/expert-opinion\\\/\",\"name\":\"Opini\u00f3n experta - AMEC Integrated Evaluation Framework\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\"},\"datePublished\":\"2016-08-22T14:45:23+00:00\",\"dateModified\":\"2024-11-25T16:41:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/expert-opinion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/expert-opinion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/expert-opinion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"material de apoio\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Opini\u00f3n experta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/\",\"name\":\"AMEC Integrated Evaluation Framework\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opini\u00f3n experta - AMEC Integrated Evaluation Framework","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Opini\u00f3n experta - AMEC Integrated Evaluation Framework","og_url":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/","og_site_name":"AMEC Integrated Evaluation Framework","article_modified_time":"2024-11-25T16:41:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/","name":"Opini\u00f3n experta - AMEC Integrated Evaluation Framework","isPartOf":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website"},"datePublished":"2016-08-22T14:45:23+00:00","dateModified":"2024-11-25T16:41:39+00:00","breadcrumb":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/expert-opinion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/"},{"@type":"ListItem","position":2,"name":"Casa","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/"},{"@type":"ListItem","position":3,"name":"material de apoio","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/"},{"@type":"ListItem","position":4,"name":"Opini\u00f3n experta"}]},{"@type":"WebSite","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/","name":"AMEC Integrated Evaluation Framework","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/comments?post=436"}],"version-history":[{"count":9,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/436\/revisions"}],"predecessor-version":[{"id":14803,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/436\/revisions\/14803"}],"up":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/565"}],"wp:attachment":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/media?parent=436"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/tags?post=436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}