{"id":427,"date":"2016-08-22T15:14:53","date_gmt":"2016-08-22T14:14:53","guid":{"rendered":"http:\/\/amecorg.com\/amecframework\/es\/?page_id=427"},"modified":"2016-08-31T13:05:20","modified_gmt":"2016-08-31T12:05:20","slug":"taxonomy","status":"publish","type":"page","link":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/","title":{"rendered":"Taxonom\u00eda"},"content":{"rendered":"<div id='top'  class='avia-section av-av_section-29380bcf3455b1959c0df92273a3ca79 main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_hr  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-427'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c av_one_full  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-7f1066956f81e6629fcde6ff239064a8\">\n#top .av_textblock_section.av-av_textblock-7f1066956f81e6629fcde6ff239064a8 .avia_textblock{\nfont-size:35px;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-7f1066956f81e6629fcde6ff239064a8 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock taxonomy-of-evaluation'  itemprop=\"text\" ><p style=\"text-align: center; margin-top: -20px;\">UNA TAXONOM\u00cdA DE LA<br \/>\nEVALUACI\u00d3N HACIA EST\u00c1NDARES<\/p>\n<\/div><\/section><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-427'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-cff9db79973b2b34cd1182f84c56818a\">\n#top .hr.av-av_hr-cff9db79973b2b34cd1182f84c56818a{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-av_hr-cff9db79973b2b34cd1182f84c56818a .hr-inner{\nwidth:300px;\nborder-color:#ff5800;\n}\n<\/style>\n<div  class='hr av-av_hr-cff9db79973b2b34cd1182f84c56818a hr-custom  avia-builder-el-3  el_after_av_section  el_before_av_one_third  avia-builder-el-first  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-6126cab7d8fab8d08143dd2dacdf673c av_one_third  avia-builder-el-4  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-70bcf6a5b8f6cf64519f651ebf272d93\">\n.flex_column.av-av_one_third-70bcf6a5b8f6cf64519f651ebf272d93{\nborder-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-70bcf6a5b8f6cf64519f651ebf272d93 av_one_third  avia-builder-el-5  el_after_av_one_third  el_before_av_one_third  jump-button flex_column_div  '     ><section  class='av_textblock_section av-av_textblock-1984e877b9f7821f9f2384c060d55255 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock jump-button'  itemprop=\"text\" ><p style=\"text-align: center;\"><a href=\"#taxonomy-table\">Un salto hacia la taxonom\u00eda<\/a><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_third-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-0aa7055fe62c3622faec82866afbaeb2 av_one_third  avia-builder-el-7  el_after_av_one_third  el_before_av_one_full  flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c av_one_full  avia-builder-el-8  el_after_av_one_third  el_before_av_section  avia-builder-el-last  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><div id=\"u6560-4\" class=\"ts-Default-Link-Style--copy clearfix colelem shared_content\" data-content-guid=\"u6560-4_content\">\n<p id=\"u6560-2\" style=\"text-align: center;\"><strong>\u00bfQu\u00e9 es una taxonom\u00eda y para qu\u00e9 sirve?<\/strong><\/p>\n<\/div>\n<div id=\"u6543-43\" class=\"ts-Default-Link-Style--copy clearfix colelem shared_content\" style=\"text-align: center;\" data-content-guid=\"u6543-43_content\"><\/div>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p id=\"u6543-2\">Existe un amplio rango de modelos de RR. PP. y de evaluaci\u00f3n de comunicaci\u00f3n mediante el uso de un amplio espectro de t\u00e9rminos que incluyen entradas, salidas, eliminaciones, productos, efectos, resultados e impacto. En cada etapa se propone un espectro aun m\u00e1s amplio de m\u00e9tricas y m\u00e9todos para la evaluaci\u00f3n. Este campo es confuso para muchos profesionales.<\/p>\n<p id=\"u6543-5\">Esta p\u00e1gina presenta una taxonom\u00eda de la evaluaci\u00f3n hecha a medida para la comunicaci\u00f3n p\u00fablica estrat\u00e9gica \u2013la taxonom\u00eda es el mapa de un campo para producir una categorizaci\u00f3n de conceptos y t\u00e9rminos\u2013, brevemente, para mostrar d\u00f3nde van las cosas y d\u00f3nde encajan unas con otras. Esta taxonom\u00eda identifica:<\/p>\n<ol id=\"u6543-15\" class=\"list0 nls-None\">\n<li id=\"u6543-8\">Las etapas principales de la comunicaci\u00f3n (como entradas, salidas, etc.);<\/li>\n<li id=\"u6543-10\">Los pasos principales en cada etapa (como ser distribuci\u00f3n de informaci\u00f3n, acogida de parte del p\u00fablico, etc.);<\/li>\n<li id=\"u6543-12\">Ejemplos de m\u00e9tricas y de hitos que pueden ser creados o identificados como parte de la evaluaci\u00f3n en cada etapa y<\/li>\n<li id=\"u6543-14\">Los m\u00e9todos usados mas com\u00fanmente para generar estas m\u00e9tricas e hitos.<\/li>\n<\/ol>\n<p id=\"u6543-18\">Una taxonom\u00eda no es lo mismo que un modelo, ya que una taxonom\u00eda intenta hacer una lista de TODOS los conceptos principales, t\u00e9rminos, m\u00e9tricas, m\u00e9todos, etc., en un campo, mientras que un modelo es la ilustraci\u00f3n de un programa o actividad espec\u00edfico para poner en pr\u00e1ctica. Sin embargo, los modelos deber\u00edan estar basados en conceptos y m\u00e9todos identificados como leg\u00edtimos en el campo e implementados en forma apropiada.<\/p>\n<p id=\"u6543-21\">Un importante beneficio de una taxonom\u00eda es que coloca conceptos, m\u00e9tricas, m\u00e9todos, etc. en su justo lugar, por ejemplo, evita que se confundan m\u00e9tricas salientes con m\u00e9tricas resultantes. Los autores del ampliamente usado texto \u201cPR Effective Public Relations, Cutlip, Center and Broom\u201d han indicado repetidamente en ediciones desde 1985 hasta avanzados los 2000 que \u201ces un error com\u00fan en programas de evaluaci\u00f3n sustituir medidas de un nivel por otras de otro nivel\u201d (1985, p. 295; 1994, p. 44; Broom, 2009, p. 358). El Profesor Em\u00e9rito de Relaciones P\u00fablicas Jim Grunig tambi\u00e9n dice que muchos profesionales usan \u201cuna m\u00e9trica obtenida en un nivel de an\u00e1lisis para mostrar el resultado de un nivel m\u00e1s alto de an\u00e1lisis\u201d (2008, p. 89). Las RR. PP. y las comunicaciones estrat\u00e9gicas no son las \u00fanicas en donde pasa esto. La muy utilizada Gu\u00eda de la Universidad de Wisconsin (UWEX) para programar modelos l\u00f3gicos de evaluaci\u00f3n dice, por ejemplo, \u201cla gente a menudo lucha con la diferencia entre salidas y resultados\u201c (Taylor-Power &amp; Henert, 2008, p. 19).<\/p>\n<p id=\"u6543-27\">Ninguna taxonom\u00eda es completa, pero la que presentamos aqu\u00ed se basa en un amplio rango de estudios de investigaci\u00f3n para ser lo m\u00e1s exhaustivos posibles (ver \u2018<a class=\"nonblock\" href=\"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/introduction\/\">Introduction to the AMEC Integrated Framework for Evaluation<\/a>\u2019)\u00a0(Introducci\u00f3n al Marco Integrado para la Evaluaci\u00f3n de AMEC) para ver detalles del origen y las bases de esta taxonom\u00eda y de la estructura misma.<\/p>\n<p id=\"u6543-30\">NOTAS PARA UTILIZAR ESTA TAXONOM\u00cdA<\/p>\n<ul id=\"u6543-39\" class=\"list0 nls-None\">\n<li id=\"u6543-32\">Los pasos, m\u00e9tricas e hitos clave no son exhaustivos ya que no todos son requeridos en cada programa. Indican t\u00edpicos acercamientos comunes a una evaluaci\u00f3n de comunicaciones p\u00fablicas como avisos, relaciones p\u00fablicas, comunicaciones de mercadotecnia, etc. Aquellos que los practican deber\u00edan elegir m\u00e9tricas relevantes e hitos y m\u00e9todos, idealmente seleccionando, por lo menos, uno de cada etapa.<\/li>\n<li id=\"u6543-34\">El arreglo de entradas, actividades, salidas, etc. no deber\u00eda ser interpretado como un simple proceso lineal. Deber\u00eda aplicarse una retroalimentaci\u00f3n de cada etapa para ajustar, afinar y cambiar la estrategia y la t\u00e1ctica si fuese necesario. La evaluaci\u00f3n es un proceso iterativo o repetitivo.<\/li>\n<li id=\"u6543-36\">No toda evaluaci\u00f3n puede mostrar un impacto, especialmente cuando la evaluaci\u00f3n se emprende dentro de un per\u00edodo relativamente corto despu\u00e9s de la comunicaci\u00f3n. El impacto a menudo se da \u201ca la larga\u201d luego de varios a\u00f1os despu\u00e9s de la comunicaci\u00f3n. Tambi\u00e9n, el objetivo de algunas comunicaciones p\u00fablicas es crear conciencia (un resultado a corto plazo) o construir confianza (un resultado intermedio) [xii]. Sin embargo, la regla general es que la evaluaci\u00f3n deber\u00eda informar mucho mas all\u00e1 de salidas y eliminaciones. La evaluaci\u00f3n deber\u00eda identificar e informar resultados m\u00ednimos y en lo posible, un impacto.<\/li>\n<li id=\"u6543-38\">Un rasgo muy importante de esta taxonom\u00eda es que el impacto incluye los resultados de impactos organizativos, de accionistas y de la sociedad. Esto se alinea con la correcta teor\u00eda de la evaluaci\u00f3n y con modelos l\u00f3gicos de programas (por ejemplo, Kellogg Foundation, 1998\/2004; Taylor-Power &amp; Henert, 2008; Wholey, 1979; Wholey, Hatry, &amp; Newcomer, 2010) y con Excellence Theory of PR, que pide que la evaluaci\u00f3n sea llevada a (a) un nivel de programaci\u00f3n (2) funcional (por ejemplo, Departamento de Unidad); (3) nivel de organizaci\u00f3n y (4) nivel societario (L. Grunig, J. Grunig &amp; Dozier, 2002, pp. 91\u201392).<\/li>\n<\/ul>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Desarrollado por el profesor Jim Macnamara de AMEC.<\/strong><\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='taxonomy-table'  class='avia-section av-av_section-3fbfd01de096a8d7639870b402802ad3 main_color avia-section-default avia-no-shadow  avia-builder-el-12  el_after_av_one_full  el_before_av_one_full  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-427'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c av_one_full  avia-builder-el-13  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center; margin-top: -57px;\"><a href=\"#top\">Back to top<\/a><\/p>\n<\/div><\/section><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-427'><div class='entry-content-wrapper clearfix'><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-9d24124a545ef7691702bdbb54c0e581\">\n.flex_column.av-av_one_full-9d24124a545ef7691702bdbb54c0e581{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-9d24124a545ef7691702bdbb54c0e581 av_one_full  avia-builder-el-15  el_after_av_section  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><div class='avia-data-table-wrap av-av_table-6f0680863dba18481f7ee32ffb67d954 avia_responsive_table avia-table-1'><table  class='avia-table avia-data-table avia_pricing_default  avia-builder-el-16  avia-builder-el-no-sibling  taxonomy-table'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Table\" ><tbody><tr class='avia-heading-row'><th class=''><b>ETAPAS<\/b> NIVEL MACRO<\/th><th class=''>ENTRADAS<sup>2<\/sup><br \/>\n<\/th><th class=''>ACTIVIDADES<\/th><th class=''>SALIDAS (OUTPUTS)<\/th><th class=''>ELIMINACIONES<sup>3<\/sup><\/th><th class=''>RESULTADOS<sup>4<\/sup><\/th><th class=''>IMPACTO<sup>5<\/sup><\/th><\/tr><tr class=''><td class=''>Definici\u00f3n abreviada<\/td><td class=''>Lo que Ud. necesita para preparar la comunicaci\u00f3n<\/td><td class=''>Cosas que Ud. hace para planificar y producir su comunicaci\u00f3n<\/td><td class=''>Lo que Ud. produce lo recibe la audiencia meta<\/td><td class=''>Lo que la audiencia hace y asimila de su comunicaci\u00f3n<\/td><td class=''>El efecto que su comunicaci\u00f3n tiene sobre la audiencia<\/td><td class=''>Los resultados causados enteramente o en parte por su comunicaci\u00f3n<\/td><\/tr><tr class=''><td class=''><b>PASOS CLAVE<\/b><br \/>\nMESO-NIVEL<\/td><td class=''><b>\u2022 Objetivos<br \/>\n\u2022 Presupuesto<br \/>\n\u2022 Recursos <\/b>(por ejemplo, personal, agencias, facilidades, asociaciones)<\/td><td class=''><b>\u2022 Investigaci\u00f3n formativa<br \/>\n\u2022 Planeamiento<sup>7<\/sup><br \/>\n\u2022 Producci\u00f3n <\/b>(por ejemplo, dise\u00f1o, escritura, compra de medios, relaciones de medios, asociaciones con medios, etc.)<\/td><td class=''><b>\u2022 Distribuci\u00f3n<br \/>\n\u2022 Exposici\u00f3n<br \/>\n\u2022 Recepci\u00f3n<sup>8<\/sup><\/b><\/td><td class=''><b>\u2022 Atenci\u00f3n<br \/>\n\u2022 Percepci\u00f3n<br \/>\n\u2022 Comprensi\u00f3n<br \/>\n\u2022 Inter\u00e9s\/agrado<br \/>\n\u2022 Compromiso<br \/>\n\u2022 Participaci\u00f3n<br \/>\n\u2022 Consideraci\u00f3n<\/b><\/td><td class=''><b>\u2022 Aprendizaje\/conocimiento<sup>9<\/sup><br \/>\n\u2022 Cambio de actitud<br \/>\n\u2022 Satisfacci\u00f3n<br \/>\n\u2022 Confianza<br \/>\n\u2022 Preferencia<br \/>\n\u2022 Intenci\u00f3n<br \/>\n\u2022 Apoyo<\/b><\/td><td class=''><b>\u2022 Reputaci\u00f3n<br \/>\n\u2022 Relaciones<br \/>\n\u2022 Conformidad\/acciones de aceptaci\u00f3n<br \/>\n\u2022 Cambio en la organizaci\u00f3n<br \/>\n\u2022 Cambio social p\u00fablico<\/b><\/td><\/tr><tr class=''><td class=''><b>EJEMPLO DE M\u00c9TRICAS E HITOS<\/b><\/p>\n<p>MICRO-NIVEL<\/td><td class=''>\u2022 Objetivos SMART<br \/>\n\u2022 Metas \/ KPI<\/td><td class=''>\u2022 Lineamientos b\u00e1sicos\/punto de referencia<br \/>\n(por ejemplo, percepci\u00f3n actual)<br \/>\n\u2022 Necesidades de la audiencia,<br \/>\npreferencias, etc.<br \/>\n\u2022 Plan estrat\u00e9gico<br \/>\n\u2022 Plan de evaluaci\u00f3n<br \/>\n\u2022 Informaci\u00f3n pre-pruebas (por ejemplo,<br \/>\nConceptos creativos<br \/>\n\u2022 Contenido producido (por ejemplo,<br \/>\nEmisiones de los medios,<br \/>\nSitios web<br \/>\n\u2022 Relaciones de los medios<\/td><td class=''>\u2022 Volumen de la publicidad<br \/>\n\u2022 Alcance de los medios<br \/>\n\u2022 Impresiones \/ OTS<br \/>\n\u2022 Voz compartida<br \/>\n\u2022 Tono\/sentimiento\/<br \/>\nfavorabilidad<br \/>\n\u2022 Mensajes colocados<br \/>\n\u2022 Posts, tweets, etc.<br \/>\n\u2022 Publicidad TARP<br \/>\n\u2022 Volumen mercadotecnia E<br \/>\n\u2022 CPM<br \/>\n\u2022 Cliqueos<br \/>\n\u2022 Presencia en eventos<\/td><td class=''>\u2022 Visitantes ocasionales<br \/>\n\u2022 Puntos de vista<br \/>\n\u2022 Respuestas (por ejemplo, seguimientos, me gusta, tags, compartir,<br \/>\nretweets)<br \/>\n\u2022 Visitantes que vuelven\/puntos de vista<br \/>\n\u2022 Recuerdo (espont\u00e1neo, o no)<br \/>\n\u2022 Comentarios positivos<br \/>\n\u2022 Respuestas positivas en encuestas, etc.<br \/>\n\u2022 Sucriptores (por ejemplo, RSS,<br \/>\nboletines)<br \/>\n\u2022 Preguntas<\/td><td class=''>\u2022 Aceptaci\u00f3n de mensajes<br \/>\n\u2022 Niveles de confianza<br \/>\n\u2022 Declaraciones de apoyo o intenci\u00f3n<br \/>\n\u2022 Gu\u00edas<br \/>\n\u2022 Registros (por ejemplo, listas de donantes de \u00f3rganos)<br \/>\n\u2022 Preferencia por una marca<br \/>\n\u2022 Trialling<br \/>\n\u2022 Asoci\u00e1ndose<br \/>\n\u2022 Reafirmando (por ejemplo, satisfacci\u00f3n del personal)<\/td><td class=''>\u2022 Apoyo del p\u00fablico<br \/>\n\u2022 Llegar a las metas (por ejemplo, donaci\u00f3n de sangre, c\u00e1ncer)<br \/>\nRevisando lista de miembros, etc.)<br \/>\n\u2022 Aumento de las ventas<br \/>\n\u2022 Aumento en las donaciones<br \/>\n\u2022 Ahorro de costos<br \/>\n\u2022 Reteniendo al personal<br \/>\n\u2022 Reteniendo a los clientes\/lealtad<br \/>\n\u2022 Aumento de la Calidad de vida \/ bienestar<\/td><\/tr><tr class=''><td class=''><b>M\u00c9TODOS<\/b><br \/>\nDE EVALUACI\u00d3N<\/td><td class=''>\u2022 An\u00e1lisis interno<br \/>\n\u2022 Examen del entorno<br \/>\n\u2022 An\u00e1lisis de Posibilidades<br \/>\n\u2022 An\u00e1lisis de riesgo<\/td><td class=''>\u2022 An\u00e1lisis de meta informaci\u00f3n (por ejemplo, investigaci\u00f3n y m\u00e9tricas pasadas)<br \/>\n\u2022 Investigaci\u00f3n de Mercado\/audiencia (por ejemplo,encuestas, grupos objetivo, entrevistas)<br \/>\n\u2022 Consultas a los interesados<br \/>\n\u2022 Estudio de casos (por ejemplo, mejores pr\u00e1cticas)<br \/>\n\u2022 An\u00e1lisis SWOT (o PEST,\u2022 PESTLE, etc.)<br \/>\n\u2022 Paneles pre-pruebas<br \/>\n\u2022 Revisi\u00f3n entre pares\/revisi\u00f3n de expertos<\/td><td class=''>\u2022 M\u00e9tricas de los medios (por ejemplo, audiencia estad\u00edsticas, impresiones, CPM)<br \/>\n\u2022 Monitoreo de los medios<br \/>\n\u2022 An\u00e1lisis del contenido de los medios (cuant)<br \/>\n\u2022 An\u00e1lisis del contenido de los medios (cual)<br \/>\n\u2022 An\u00e1lisis de medios sociales (cuant.y cual.)<br \/>\n\u2022 Informes sobre actividades (por ejemplo, eventos, patronazgos)<\/td><td class=''>\u2022 Estad\u00edsticas de la Web (por ejemplo, descarga de puntos de vista)<br \/>\n\u2022 An\u00e1lisis de medios sociales (cual. \u2013 por ejemplo, comentarios)<br \/>\n\u2022 Retroalimentaci\u00f3n (por ejemplo,comentarios, cartas)<br \/>\n\u2022 Etnograf\u00eda<sup>10<\/sup><br \/>\n(observaci\u00f3n)<br \/>\n\u2022 Etnograf\u00eda net<sup>11<\/sup> (etnograf\u00eda online)<br \/>\n\u2022 Encuesta de audiencia (por ejemplo, re<br \/>\nConciencia, comprensi\u00f3n,<br \/>\nInter\u00e9s, opini\u00f3n)<br \/>\n\u2022 Grupo enfocado (como arriba)<br \/>\n<\/td><td class=''>\u2022 An\u00e1lisis del medio social (cual.)<br \/>\n\u2022 Estad\u00edsticas de base de datos (por ejemplo,<br \/>\nSiguiendo encuestas, identificando fuentes)<br \/>\n\u2022Etnograf\u00eda<br \/>\n(observaci\u00f3n)<br \/>\n\u2022 Etnograf\u00eda en la red (etnograf\u00eda online)<br \/>\n\u2022 Consultas de opini\u00f3n<br \/>\n\u2022 Encuesta de agentes (por ejemplo,<br \/>\nre-satisfacci\u00f3n, confianza)<br \/>\n\u2022 Grupos objetivos (como arriba)<br \/>\n\u2022 Entrevistas (como arriba)<br \/>\n\u2022 Conteo de Promotor de Net (NPS)<sup>12<\/sup><\/td><td class=''>\u2022 Registros de base de datos (por ejemplo,<br \/>\nDonaciones de sangre, resultados en salud, membres\u00eda, etc.)<br \/>\n\u2022 Llevando cuenta de las ventas<br \/>\n\u2022 Llevando cuenta de las donaciones<br \/>\n\u2022 Informaci\u00f3n sobre CRM<br \/>\n\u2022Informaci\u00f3n sobre encuesta al personal<br \/>\n\u2022 Estudios sobre reputaci\u00f3n<br \/>\n\u2022 An\u00e1lisis Costo Beneficio\/Proporci\u00f3n Beneficio Costo<br \/>\n\u2022 ROI (si hay objetivos financieros)<br \/>\n\u2022 Econom\u00e9tricas<sup>13<\/sup><br \/>\n\u2022 Escalas de calidad de vida &amp; mediciones del bienestar<\/td><\/tr><\/tbody><\/table><\/div><style type='text\/css'>.avia-table-1 td:nth-of-type(1):before { content: 'ETAPAS NIVEL MACRO'; } .avia-table-1 td:nth-of-type(2):before { content: 'ENTRADAS2\n'; } .avia-table-1 td:nth-of-type(3):before { content: 'ACTIVIDADES'; } .avia-table-1 td:nth-of-type(4):before { content: 'SALIDAS (OUTPUTS)'; } .avia-table-1 td:nth-of-type(5):before { content: 'ELIMINACIONES3'; } .avia-table-1 td:nth-of-type(6):before { content: 'RESULTADOS4'; } .avia-table-1 td:nth-of-type(7):before { content: 'IMPACTO5'; } <\/style><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-35ffba341a9e5797256bba7ad31f3cf0\">\n.flex_column.av-av_one_full-35ffba341a9e5797256bba7ad31f3cf0{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-35ffba341a9e5797256bba7ad31f3cf0 av_one_full  avia-builder-el-17  el_after_av_one_full  el_before_av_one_full  supporting-footnotes-taxonomy first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>NOTAS AL PIE DE APOYO A LA TAXONOM\u00cdA DE LA EVALUACI\u00d3N<\/strong><\/p>\n<ol id=\"u7065-36\" class=\"list0 nls-None\">\n<li id=\"u7065-5\" style=\"text-align: left;\">La confianza se considera un resultado intermedio porque es buscada para lograr un impacto a un plazo m\u00e1s largo, como ser elegido para gobernar, clientes que siguen haciendo negocios con una compa\u00f1\u00eda, etc. No es una meta final en s\u00ed misma. Algunos modelos de programa l\u00f3gico se refieren a ella como la primera etapa de Entradas\/Recursos.<\/li>\n<li id=\"u7065-7\" style=\"text-align: left;\">Algunas retenciones avanzadas pueden sobrepasar o ser lo mismo que los resultados a corto plazo. Y esto es por qu\u00e9 los modelos l\u00f3gicos de programa m\u00e1s usados no usan retenciones en esta etapa. Las etenciones y los resultados pueden ser cognitivos y\/o afectivos (emocionales) y\/o conativos (de conducta).<\/li>\n<li id=\"u7065-9\" style=\"text-align: left;\">Los resultados a largo plazo sobrepasan al impacto y a veces se consideran lo mismo.<\/li>\n<li id=\"u7065-11\" style=\"text-align: left;\">El impacto es a menudo evaluado solamente en relaci\u00f3n con la organizaci\u00f3n. Sin embargo como se hizo notar en la introducci\u00f3n, los interesados, los p\u00fablicos y la sociedad como un todo deben ser tenidos en cuenta. Esto es esencial para organizaciones gubernamentales, no gubernamentales y sin fines de lucro enfocadas en servir al inter\u00e9s p\u00fablico. Pero tambi\u00e9n el impacto sobre los interesados y la sociedad afecta y da forma al entorno en el cual operan los negocios. (es decir, esta evaluaci\u00f3n forma parte del examen del entorno, investigaci\u00f3n de audiencia, y de mercado que informar\u00e1n a la planificaci\u00f3n futura).<\/li>\n<li id=\"u7065-13\" style=\"text-align: left;\">La causalidad es muy dif\u00edcil de establecer en muchos casos, especialmente cuando numerosas influencias confluyen en el impacto (resultados), como sucede a menudo. Las tres reglas clave de la causalidad deben ser aplicadas (a) la causa alegada debe preceder el efecto\/impacto alegado, (b) debe haber una relaci\u00f3n clara entre la causa alegada y efecto (por ejemplo, debe haber evidencia de que la audiencia tuvo acceso a y us\u00f3 la informaci\u00f3n que Ud. le provey\u00f3) y (c) otras causas posibles deben ser desechadas.<\/li>\n<li id=\"u7065-15\" style=\"text-align: left;\">Algunas personas incluyen planificaci\u00f3n en entradas o alimentaci\u00f3n. Sin embargo, si esto sucede, la investigaci\u00f3n formativa (que debe preceder a la planificaci\u00f3n) tambi\u00e9n debe ser incluida en entradas o alimentaci\u00f3n. No obstante, la mayor\u00eda de los modelos de evaluaci\u00f3n de programa identifican a la investigaci\u00f3n y la planificaci\u00f3n como actividades clave para ser llevadas a cabo como parte del programa de comunicaci\u00f3n. Las entradas son generalmente pre-campa\u00f1a y pre-programa.<\/li>\n<li id=\"u7065-17\" style=\"text-align: left;\">La recepci\u00f3n se refiere a la informaci\u00f3n o a los mensajes recibidos por la audiencia meta y es ligeramente diferente a la exposici\u00f3n. Por ejemplo, una audiencia puede estar expuesta a una historia en los medios a los cuales tiene acceso, pero puede pasar por alto la historia y as\u00ed no recibir la informaci\u00f3n. De manera similar, pueden estar presentes en un evento como una feria comercial y estar expuestos a los contenidos, pero no recibir informaci\u00f3n o mensajes (por ejemplo, por falta de atenci\u00f3n, o selecci\u00f3n de contenidos en los cuales enfocarse).<\/li>\n<li id=\"u7065-19\" style=\"text-align: left;\">Aprender: (es decir, adquisici\u00f3n de conocimiento) no se lo requiere en todos los casos. Sin embargo, en algunas campa\u00f1as de comunicaci\u00f3n p\u00fablica y proyectos s\u00ed se requiere. Por ejemplo, campa\u00f1as de salud para promover alimentos ricos en calcio y suplementos para disminuir la osteoporosis en las mujeres encontraron que primero las mujeres deb\u00edan ser instruidas sobre la osteoporosis (qu\u00e9 es, sus causas, etc.). De manera similar, combatir la obesidad necesita instrucci\u00f3n sobre dietas. Mientras que la comprensi\u00f3n se refiere a la comprensi\u00f3n de mensajes comunicados, aprender se refiere a la adquisici\u00f3n de conocimientos m\u00e1s profundos o m\u00e1s amplios, lo cual es necesario para lograr los objetivos.<\/li>\n<li id=\"u7065-21\" style=\"text-align: left;\">La etnograf\u00eda es un m\u00e9todo de investigaci\u00f3n basado en la observaci\u00f3n intensiva de primera mano a trav\u00e9s de un per\u00edodo extenso, a menudo complementado con entrevistas y otros m\u00e9todos de investigaci\u00f3n.<\/li>\n<li id=\"u7065-23\" style=\"text-align: left;\">Etnograf\u00eda \u201cnet\u201d es etnograf\u00eda online, en la cual los usuarios online son monitoreados atentamente para identificar sus patrones de conducta, actitudes, etc. a trav\u00e9s e sus comentarios, rastro de clics, y otras m\u00e9tricas digitales.<\/li>\n<li id=\"u7065-25\" style=\"text-align: left;\">El conteo de promotor de la red es un conteo de hasta 10 basado en una \u00fanica pregunta. \u00bfQu\u00e9 tan posible es que Ud. le recomiende (una marca) a un amigo o colega? Los resultados que van de 0 a 6 se consideran detractores\/insatisfechos, los resultados de 7-8 se consideran satisfechos pero no entusiastas y los resultados de 9-10 son los considerados seguidores leales, entusiastas y seguidores. (Ver <a href=\"https:\/\/www.netpromoter.com\/know\">https:\/\/www.netpromoter.com\/know<\/a>)<\/li>\n<li id=\"u7065-30\" style=\"text-align: left;\">La econom\u00e9trica es la aplicaci\u00f3n de matem\u00e1ticas y m\u00e9todos estad\u00edsticos para probar hip\u00f3tesis e identificar las relaciones econ\u00f3micas entre factores basados en informaci\u00f3n emp\u00edrica (ver <a href=\"http:\/\/www.dummies.com\/how-to\/content\/econometrics-for-dummies-cheat-sheet.html\">http:\/\/www.dummies.com\/how-to\/content\/econometrics-for-dummies-cheat-sheet.html<\/a>)<\/li>\n<\/ol>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-ce7704e8c9803d552aabd216f86414ca\">\n.flex_column.av-av_one_full-ce7704e8c9803d552aabd216f86414ca{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-ce7704e8c9803d552aabd216f86414ca av_one_full  avia-builder-el-19  el_after_av_one_full  el_before_av_one_full  abbreviations-taxonomy first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-7b28236849ea9d61f0d419b81fd4954a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock abbreviations'  itemprop=\"text\" ><p><strong>ABREVIACIONES<\/strong><br \/>\nCPM Costo por mil<br \/>\nCRM Manejo de la relaci\u00f3n con los clientes (informaci\u00f3n com\u00fanmente hallada en bases de datos CRM)<br \/>\nKPI Indicador clave del desempe\u00f1o (ver http:\/\/www.ap-institute.com\/what-is-a-key-performance-indicator.aspx)<br \/>\nOTS Oportunidades para ver (usualmente calculadas lo mismo que impresiones\u2019)<br \/>\nPEST Estructura de evaluaci\u00f3n que examina factores pol\u00edticos, econ\u00f3micos, sociales y tecnol\u00f3gicos)<br \/>\nPESTLE Una estructura de evaluaci\u00f3n que examina factores pol\u00edticos, econ\u00f3micos sociales, tecnol\u00f3gicos, legales y de entorno (ver http:\/\/pestleanalysis.com\/how-to-do-a-swot-analysis).<br \/>\nROI Beneficio o ganancia de la inversi\u00f3n<br \/>\nSMART Se refiere a objetivos que son espec\u00edficos, medibles, que se pueden llevar a cabo, relevantes (por ejemplo, relacionados con objetivos organizativos) y ligados a un per\u00edodo de tiempo (por ejemplo, dentro de un per\u00edodo de tiempo espec\u00edfico)<br \/>\nSWOT M\u00e9todo estrat\u00e9gico de planificaci\u00f3n que examina puntos fuertes, puntos d\u00e9biles, oportunidades, y amenazas.<br \/>\nTARP Puntaje de audiencia objetivo basado en un sistema de puntaje usado en publicidad. (ver http:\/\/www.multimediabuying.com.au\/faq)<br \/>\nUWEX Programa de Extensi\u00f3n de la Universidad de Wisconsin (ver Taylor-Power &amp; Henert, 2008)<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-0fd34ff97a6f55f6d4f438eeabb9a7c1\">\n.flex_column.av-av_one_full-0fd34ff97a6f55f6d4f438eeabb9a7c1{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-0fd34ff97a6f55f6d4f438eeabb9a7c1 av_one_full  avia-builder-el-21  el_after_av_one_full  avia-builder-el-last  references-taxonomy first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-787aaea060e08877c1e025c4d1d99375 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock references'  itemprop=\"text\" ><p><strong>REFERENCES &amp; FURTHER INFORMATION<\/strong><br \/>\nBroom, G. (2009). Cutlip &amp; Center\u2019s effective public relations (10th ed.). Upper Saddle River, NJ: Pearson.<br \/>\nCutlip, S., Center, A., &amp; Broom, G. (1985). Effective public relations (6th ed.). Englewood Cliffs, NJ: Prentice Hall.<br \/>\nCutlip, S., Center, A., &amp; Broom, G. (1994). Effective public relations (7th ed). Upper Saddle River, NJ: Prentice Hall.<br \/>\nGrunig, J. (2008). Conceptualizing quantitative research in public relations. In B. van Ruler, A. Tkalac Ver\u0109i\u0109, &amp; D. Ver\u0109i\u0109 (Eds.), Public relations metrics: research and evaluation (pp. 88\u2013119). New York, NY: Routledge.<br \/>\nGrunig, L., Grunig J., &amp; Dozier, D. (2002). Excellent organizations and effective organizations: A study of communication management in three countries. Mahwah, NJ: Lawrence Erlbaum.<br \/>\nStacks, D., &amp; Bowen, S. (Eds.). (2013). Dictionary of public relations measurement and research. Gainesville FL: Institute for Public Relations. Available at<a class=\"nonblock\" href=\"http:\/\/www.instituteforpr.org\/topics\/dictionary-of-public-relations-measurement-and-research\" target=\"_blank\">http:\/\/www.instituteforpr.org\/topics\/dictionary-of-public-relations-measurement-and-research<\/a><br \/>\nTaylor-Power, E., &amp; Henert, E. (2008). Developing a logic model: Teaching and training guide. Retrieved from<a class=\"nonblock\" href=\"http:\/\/www.uwex.edu\/ces\/pdande\/evaluation\/pdf\/lmguidecomplete.pdf\" target=\"_blank\">http:\/\/www.uwex.edu\/ces\/pdande\/evaluation\/pdf\/lmguidecomplete.pdf<\/a><br \/>\nWholey, J. (1979). Evaluation: Promise and performance. Washington, DC: Urban Institute Press.<br \/>\nWholey J., Hatry, H., &amp; Newcomer, K. (Eds.). (2010). Handbook of practical program evaluation (3rd ed.). San Francisco, CA: Jossey-Bass.<\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":565,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"class_list":["post-427","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taxonom\u00eda - AMEC Integrated Evaluation Framework<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taxonom\u00eda - AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/\" \/>\n<meta property=\"og:site_name\" content=\"AMEC Integrated Evaluation Framework\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-31T12:05:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/taxonomy\\\/\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/taxonomy\\\/\",\"name\":\"Taxonom\u00eda - AMEC Integrated Evaluation Framework\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\"},\"datePublished\":\"2016-08-22T14:14:53+00:00\",\"dateModified\":\"2016-08-31T12:05:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/taxonomy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/taxonomy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/taxonomy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"material de apoio\",\"item\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/es\\\/home\\\/supporting-material\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Taxonom\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/\",\"name\":\"AMEC Integrated Evaluation Framework\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amec.blazedev.co.uk\\\/amecframework\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taxonom\u00eda - AMEC Integrated Evaluation Framework","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Taxonom\u00eda - AMEC Integrated Evaluation Framework","og_url":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/","og_site_name":"AMEC Integrated Evaluation Framework","article_modified_time":"2016-08-31T12:05:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/","name":"Taxonom\u00eda - AMEC Integrated Evaluation Framework","isPartOf":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website"},"datePublished":"2016-08-22T14:14:53+00:00","dateModified":"2016-08-31T12:05:20+00:00","breadcrumb":{"@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/taxonomy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/"},{"@type":"ListItem","position":2,"name":"Casa","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/"},{"@type":"ListItem","position":3,"name":"material de apoio","item":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/home\/supporting-material\/"},{"@type":"ListItem","position":4,"name":"Taxonom\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/#website","url":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/","name":"AMEC Integrated Evaluation Framework","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amec.blazedev.co.uk\/amecframework\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":7,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/427\/revisions"}],"predecessor-version":[{"id":663,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/427\/revisions\/663"}],"up":[{"embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/pages\/565"}],"wp:attachment":[{"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amec.blazedev.co.uk\/amecframework\/es\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}